{"id":52687,"date":"2025-03-27T17:23:28","date_gmt":"2025-03-27T16:23:28","guid":{"rendered":"https:\/\/www.fluidra.com\/commercial-solutions\/inspiration\/blog\/resorts-con-lagunas\/"},"modified":"2025-08-05T10:18:10","modified_gmt":"2025-08-05T08:18:10","slug":"resorts-amb-llacunes","status":"publish","type":"new","link":"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/","title":{"rendered":"Resorts con lagunas: por qu\u00e9 las lagunas artificiales mejoran los negocios hoteleros"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Taula de continguts<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#Los_resorts_con_lagunas_definicion_y_diseno\" >Los resorts con lagunas: definici\u00f3n y dise\u00f1o<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#Playas_y_zonas_de_bano_tipo_piscina\" >Playas y zonas de ba\u00f1o tipo piscina<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#Una_extensa_y_variada_oferta_de_actividades_y_servicios\" >Una extensa y variada oferta de actividades y servicios<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#Sistemas_de_tratamiento_y_recirculacion_de_agua\" >Sistemas de tratamiento y recirculaci\u00f3n de agua<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#Los_beneficios_de_los_resorts_con_laguna_para_los_operadores\" >Los beneficios de los resorts con laguna para los operadores<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#%C2%BFPor_que_los_huespedes_prefieren_los_resorts_con_lagunas\" >\u00bfPor qu\u00e9 los hu\u00e9spedes prefieren los resorts con lagunas?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/resorts-amb-llacunes\/#Resorts_con_laguna_por_que_son_el_futuro_de_la_hosteleria\" >Resorts con laguna: por qu\u00e9 son el futuro de la hosteler\u00eda<\/a><\/li><\/ul><\/nav><\/div>\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Los_resorts_con_lagunas_definicion_y_diseno\"><\/span><strong>Los resorts con lagunas: definici\u00f3n y dise\u00f1o<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Las lagunas artificiales son <strong>maravillas de la ingenier\u00eda moderna, <\/strong>que combinan tecnolog\u00eda punta con un dise\u00f1o cuidado para crear espacios acu\u00e1ticos impresionantes.<\/p>\n\n\n\n<p>La pieza central dentro de un resort y de su oferta de entretenimiento, las lagunas artificiales suelen estar rodeadas de m\u00faltiples servicios como tiendas, bares y restaurantes. Adem\u00e1s, tambi\u00e9n se convierten en un eje central de entretenimiento acu\u00e1tico, incluyendo espect\u00e1culos o alquiler de deportes acu\u00e1ticos, entre otras opciones.<\/p>\n\n\n\n<p>El resultado es un resort con laguna integral que ofrece una multitud de posibilidades de entretenimiento, todo dentro de un paisaje \u00fanico dise\u00f1ado para sumergir a los hu\u00e9spedes en un entorno tranquilo pero vibrante.<\/p>\n\n\n\n<p>El atractivo est\u00e9tico de la laguna reside a menudo en su semejanza con un <strong>entorno tropical, <\/strong>con playas de arena, formas org\u00e1nicas y palmeras. Para lograr su impresionante apariencia, estas lagunas dependen de <strong>un dise\u00f1o bien pensado <\/strong>que tambi\u00e9n debe abarcar un sistema cuidadosamente planificado de \u00e1reas interconectadas<strong> <\/strong>para que la funcionalidad no se vea comprometida.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXdDR5s3J38nUvQ-jx4AhQ5vb4eoQmFExQVY5rx6Qi2ZCuKoPizc-SPx4cYYWkmbYSbrEj3K8aTPdDz7YffFQ4h7TV_f53qHcLZvtUTTsMQP3E51VBmgxXvFg7ocfDM8CD4ZK7awGw?key=O7dbRxWrhHoVWrqUuECuqsxU\" alt=\"\" title=\"\"><\/figure>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1xG4FlUJ1TwKWaQ45LmtHb5s3YVktdKCn\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n\n\n\n<p>A continuaci\u00f3n veremos algunos de los elementos clave que componen un resort con laguna completamente funcional y bien dise\u00f1ado:<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Playas_y_zonas_de_bano_tipo_piscina\"><\/span><strong>Playas y zonas de ba\u00f1o tipo piscina<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Las lagunas artificiales suelen tener extensas playas de arena que imitan un entorno costero natural. Estas \u00e1reas<strong> <\/strong>est\u00e1n dise\u00f1adas para soportar un uso frecuente y al mismo tiempo mantener una sensaci\u00f3n suave y natural para los hu\u00e9spedes.<\/p>\n\n\n\n<p>Por otro lado, algunas \u00e1reas est\u00e1n dise\u00f1adas con un <strong>acabado tipo piscina, <\/strong>que cuentan con paredes s\u00f3lidas y crean un ambiente de nataci\u00f3n m\u00e1s estructurado y cerrado que puede resultar m\u00e1s atractivo para ciertos ba\u00f1istas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Una_extensa_y_variada_oferta_de_actividades_y_servicios\"><\/span><strong>Una extensa y variada oferta de actividades y servicios<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>Los resorts con lagunas artificiales pueden dise\u00f1arse para satisfacer una amplia gama de preferencias de los hu\u00e9spedes. Por ello, ofrecen varias <strong>zonas recreativas<\/strong>, entre ellas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Zonas de ba\u00f1o<\/li>\n\n\n\n<li>Zonas de deportes acu\u00e1ticos (kayak, paddle surf, etc)<\/li>\n\n\n\n<li>Zonas para tomar el sol<\/li>\n\n\n\n<li>Zonas peatonales pintorescas que tambi\u00e9n incluyen bares y restaurantes.<\/li>\n<\/ul>\n\n\n\n<p>Adem\u00e1s<strong>, una iluminaci\u00f3n bien pensada, fuentes y <\/strong><a href=\"https:\/\/www.fluidra.com\/projects\/mesmerizing-water-shows\/\"><strong>espect\u00e1culos acu\u00e1ticos <\/strong><\/a>permiten que las lagunas artificiales extiendan su atractivo hasta las horas nocturnas, de modo que el ambiente es impresionante tanto de d\u00eda como de noche.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Sistemas_de_tratamiento_y_recirculacion_de_agua\"><\/span><strong>Sistemas de tratamiento y recirculaci\u00f3n de agua<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h3>\n\n\n\n<p>En el coraz\u00f3n de cada laguna artificial se encuentra su <strong>sistema de tratamiento de agua<\/strong>. Responsable de garantizar que el agua sea <strong>cristalina y segura <\/strong>en todo momento, el sistema de filtraci\u00f3n puede dise\u00f1arse con la eficiencia como prioridad, incluyendo opciones como <a href=\"https:\/\/www.fluidra.com\/projects\/sand-filters-for-swimming-pools\/\"><strong>filtros de arena<\/strong><\/a>, <a href=\"https:\/\/www.fluidra.com\/ca\/?p=21401\"><strong>filtros regenerativos <\/strong><\/a><strong>con perlita <\/strong>o sistemas de desinfecci\u00f3n automatizados a base de <strong>cloro y <\/strong><a href=\"https:\/\/www.fluidra.com\/ca\/?p=21442\"><strong>desinfecci\u00f3n UV <\/strong><\/a>que mantienen el agua libre de bacterias y algas, asegurando el cumplimiento de las normas sanitarias.<\/p>\n\n\n\n<p>Otro elemento clave para cualquier resort tipo laguna es un <strong>sistema de circulaci\u00f3n eficiente, <\/strong>que garantiza un movimiento constante del agua, evitando el estancamiento y promoviendo una limpieza uniforme. Para ello, el sistema de circulaci\u00f3n utiliza <strong>skimmers <\/strong>y desag\u00fces de fondo para recolectar el agua y <strong>bombas de alta eficiencia <\/strong>en lugares estrat\u00e9gicos que permiten reducir la cantidad de tuber\u00edas.<strong> <\/strong>Cuando se dise\u00f1a adecuadamente, este flujo de agua es capaz de minimizar las p\u00e9rdidas de energ\u00eda y al mismo tiempo garantizar que el agua de la laguna permanece pr\u00edstina.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXen7n8kXuioDb1-coFL4l1II7lBgDh6cYMSi3KrCwXulBF6c66phN79xVXaxj2OZfTJqV99EFw9WA0GeSXdNnrjTkicbHf3lP1g__GOixQKgvirl1wTRnIvw71AWLVwIWQS_UiL_g?key=O7dbRxWrhHoVWrqUuECuqsxU\" alt=\"\" title=\"\"><\/figure>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/15rfAapjU1PQrwnPXfB29tJuRVs0Fp3bM\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Los_beneficios_de_los_resorts_con_laguna_para_los_operadores\"><\/span><strong>Los beneficios de los resorts con laguna para los operadores<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para los operadores de complejos tur\u00edsticos, la integraci\u00f3n de una laguna no es solo una mejora est\u00e9tica, sino tambi\u00e9n una <strong>inversi\u00f3n estrat\u00e9gica que impulsa la rentabilidad <\/strong>y al mismo tiempo mantiene la eficiencia operativa. De hecho, a continuaci\u00f3n se indican tres razones clave por las que los resorts con laguna son beneficiosos para los operadores:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Diferenciaci\u00f3n del mercado y atracci\u00f3n de hu\u00e9spedes<\/strong>: una laguna artificial representa una caracter\u00edstica de lujo \u00fanica que atrae a hu\u00e9spedes e inversores que buscan servicios y opciones de entretenimiento exclusivos. En un mercado hotelero abarrotado, los resorts con laguna destacan y atraen a una amplia audiencia que busca destinos vacacionales \u00fanicos y de primer nivel, desde parejas y familias hasta organizadores de eventos corporativos.<\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Mayores ingresos y retorno de la inversi\u00f3n<\/strong>: los estudios han demostrado que tanto los servicios circundantes como las propiedades cercanas a zonas acu\u00e1ticas suelen generar mayores ingresos. Incluir una laguna en un proyecto aumenta el valor de la propiedad, pero eso no es todo. Tambi\u00e9n aumenta el retorno de la inversi\u00f3n a trav\u00e9s de servicios y actividades adicionales y mayores \u00edndices de estad\u00edas prolongadas de los hu\u00e9spedes, adem\u00e1s de justificar precios m\u00e1s altos, lo que aumenta las tarifas promedio por habitaci\u00f3n.<\/li>\n<\/ol>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Optimizaci\u00f3n y eficiencia del espacio<\/strong>: Las lagunas se adaptan a cualquier tipo de proyecto, tama\u00f1o y forma. Tambi\u00e9n se pueden construir para maximizar el terreno disponible mediante el uso de salas t\u00e9cnicas m\u00e1s peque\u00f1as y descentralizadas y sistemas de tuber\u00edas optimizados. Una opci\u00f3n que reduce significativamente el espacio necesario para las instalaciones mec\u00e1nicas y, al mismo tiempo, disminuye los niveles generales de consumo de energ\u00eda. Adem\u00e1s, la integraci\u00f3n de sistemas automatizados implica eficiencias adicionales y, al mismo tiempo, ofrece tranquilidad a los operadores al elegir una soluci\u00f3n abierta sin tarifas de propiedad.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXc5Q830wAY9SaJyk4x0YZhC4elc0S1-S0aiCLfegZtVRH4X7h64XR-O2jR2ysnTmYp7OE3Lrl8MRjDRLmYoTlndtNeZrXWbl0K4wvzQMOJPnW5c6RMgYjPoq3MJleQZqb30Kr_1Yg?key=O7dbRxWrhHoVWrqUuECuqsxU\" alt=\"\" title=\"\"><\/figure>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/1fKRx37iH2vrmwJqkLgzLdVBMJavVr1Ip\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"%C2%BFPor_que_los_huespedes_prefieren_los_resorts_con_lagunas\"><\/span><strong>\u00bfPor qu\u00e9 los hu\u00e9spedes prefieren los resorts con lagunas?<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Para los visitantes, las lagunas artificiales redefinen su experiencia vacacional al ofrecer una escapada \u00fanica y lujosa que las piscinas tradicionales o incluso los complejos tur\u00edsticos frente al mar no siempre pueden reproducir. A continuaci\u00f3n, se enumeran tres razones principales por las que los hu\u00e9spedes adoran los resorts con lagunas:<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li><strong>Una experiencia de playa en cualquier lugar<\/strong>: los resorts con lagunas brindan un oasis tropical incluso en lugares sin salida al mar. Sus playas de arena y aguas cristalinas invitan a los hu\u00e9spedes a disfrutar de un ambiente lujoso frente al mar sin tener que viajar hasta la costa.<\/li>\n<\/ol>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li><strong>Entorno seguro y controlado<\/strong>: A diferencia de las playas naturales, las lagunas artificiales ofrecen un entorno controlado, libre de algunos de los inconvenientes m\u00e1s importantes de las lagunas reales (olas, fuertes corrientes, animales potencialmente peligrosos\u2026). Esto las hace perfectas para familias con ni\u00f1os o personas que buscan una experiencia sin preocupaciones.<\/li>\n<\/ol>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li><strong>Actividades infinitas<\/strong>: desde deportes acu\u00e1ticos hasta relajaci\u00f3n en la playa, un resort con laguna ofrece oportunidades de entretenimiento para todos, garantizando que cada hu\u00e9sped encuentre algo que le guste.<\/li>\n<\/ol>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/lh7-rt.googleusercontent.com\/docsz\/AD_4nXe8elH3U8Kwmr7LV5Q23lzw85q6w7LsegfEmUC2E3ONEVqzUMw6i2vsalHGwrfVxPm46Hl_uivaMsLESq9dpkNbCUEeROfV72Bu1l6dsvgZ6uoOAxF0g5P0Vh_amMWvbU6Ad-1h?key=O7dbRxWrhHoVWrqUuECuqsxU\" alt=\"\" title=\"\"><\/figure>\n\n\n\n<p><a href=\"https:\/\/drive.google.com\/file\/d\/10XfhHXvWnDeGDxx-227Zlo-86GubFQTI\/view?usp=sharing\" target=\"_blank\" rel=\"noopener\"><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Resorts_con_laguna_por_que_son_el_futuro_de_la_hosteleria\"><\/span><strong>Resorts con laguna: por qu\u00e9 son el futuro de la hosteler\u00eda<\/strong><span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>A medida que los viajeros buscan <strong>experiencias \u00fanicas e inmersivas, <\/strong>los resorts con laguna se est\u00e1n convirtiendo en sin\u00f3nimo de lujo, innovaci\u00f3n y experiencias vacacionales \u00fanicas.<\/p>\n\n\n\n<p>Su capacidad de reproducir un para\u00edso tropical en casi cualquier ubicaci\u00f3n los convierte en una opci\u00f3n atractiva tanto para operadores como para hu\u00e9spedes. Pero su atractivo va m\u00e1s all\u00e1 de la est\u00e9tica: cuando est\u00e1n bien dise\u00f1ados, los resorts con laguna pueden <a href=\"https:\/\/www.fluidra.com\/projects\/positive-pools\/?_gl=1*1v53bnr*_up*MQ..*_ga*MTY2Mjk2MzQ4MC4xNzM4ODMzMzQ5*_ga_6CPK6086Q4*MTczODgzMzM0OC4xLjEuMTczODgzMzM1Mi4wLjAuMA..\">alinearse con la creciente demanda de turismo sostenible e ir m\u00e1s all\u00e1 de la mera eficiencia<\/a>, contribuyendo a un futuro sostenible y socialmente responsable.<\/p>\n\n\n\n<p>Integrar una laguna a su resort no solo <strong>agrega un \u201cfactor sorpresa\u201d<\/strong>: <strong>transforma toda la experiencia del hu\u00e9sped<\/strong>, mejora la rentabilidad y garantiza la sostenibilidad a largo plazo.<\/p>\n\n\n\n<p>En este contexto, las lagunas artificiales se han convertido en una inversi\u00f3n gratificante para los operadores que buscan mantenerse a la vanguardia en el cada vez m\u00e1s competitivo mercado hotelero.<\/p>\n\n\n\n<p>Si buscas elevar la oferta de ocio de tu resort, considera <a href=\"https:\/\/www.fluidra.com\/projects\/hospitality-lakes-and-lagoons\/?_gl=1*12jrut2*_up*MQ..*_ga*MTY2Mjk2MzQ4MC4xNzM4ODMzMzQ5*_ga_6CPK6086Q4*MTczODgzNzQzMC4yLjAuMTczODgzNzQzMC4wLjAuMA..\"><strong>los lagos y lagunas de hospitalidad <\/strong><\/a>como una oportunidad \u00fanica donde la tecnolog\u00eda se une a la tranquilidad, construyendo un <strong>trocito de para\u00edso que eleva las experiencias de los hu\u00e9spedes <\/strong>y transforma su estancia en una escapada inolvidable.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los resorts con lagunas: definici\u00f3n y dise\u00f1o Las lagunas artificiales son maravillas de la ingenier\u00eda moderna, que combinan tecnolog\u00eda punta con un dise\u00f1o cuidado para crear espacios acu\u00e1ticos impresionantes. La pieza central dentro de un resort y de su oferta de entretenimiento, las lagunas artificiales suelen estar rodeadas de m\u00faltiples servicios como tiendas, bares y [&hellip;]<\/p>\n","protected":false},"author":18,"featured_media":48763,"template":"","meta":{"_acf_changed":true},"new-category":[2164],"class_list":["post-52687","new","type-new","status-publish","has-post-thumbnail","hentry","new-category-lagoon-ca"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/new\/52687","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/types\/new"}],"author":[{"embeddable":true,"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/users\/18"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/media\/48763"}],"wp:attachment":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/media?parent=52687"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/new-category?post=52687"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}