{"id":52804,"date":"2022-03-09T10:00:32","date_gmt":"2022-03-09T09:00:32","guid":{"rendered":"https:\/\/www.fluidra.com\/commercial-solutions\/inspiration\/blog\/agua-turbia-en-un-spa-como-evitarla\/"},"modified":"2025-08-05T10:19:35","modified_gmt":"2025-08-05T08:19:35","slug":"aigua-terbola-en-un-spa-com-evitar-la","status":"publish","type":"new","link":"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/aigua-terbola-en-un-spa-com-evitar-la\/","title":{"rendered":"Agua turbia en un spa: c\u00f3mo evitarla"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Taula de continguts<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/aigua-terbola-en-un-spa-com-evitar-la\/#%C2%BFQue_es_el_agua_turbia\" >\u00bfQu\u00e9 es el agua turbia?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/aigua-terbola-en-un-spa-com-evitar-la\/#%C2%BFQue_causa_el_agua_turbia_en_un_spa\" >\u00bfQu\u00e9 causa el agua turbia en un spa?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/aigua-terbola-en-un-spa-com-evitar-la\/#Como_evitar_la_formacion_de_agua_turbia\" >C\u00f3mo evitar la formaci\u00f3n de agua turbia<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/inspiracio\/bloc\/aigua-terbola-en-un-spa-com-evitar-la\/#Mantener_el_spa_libre_de_agua_turbia\" >Mantener el spa libre de agua turbia<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_es_el_agua_turbia\"><\/span>\u00bfQu\u00e9 es el agua turbia?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>El agua turbia es un t\u00e9rmino que se utiliza para describir el agua que se ve brumosa y ofrece un aspecto desagradable. Por lo general, cuando esto ocurre no se puede ver el fondo de la piscina porque el agua se ha mezclado con muchas part\u00edculas diminutas que reflejan la luz del entorno.<\/p>\n<p>Las part\u00edculas existentes en agua turbia oscilan entre 0,5 y 5 micras, por lo que son imposibles de detectar a simple vista. Normalmente aparecen debido a un desajuste en los productos qu\u00edmicos, mala filtraci\u00f3n u otros factores ambientales.<\/p>\n<p>Por supuesto la principal preocupaci\u00f3n es que el agua se ve poco atractiva, pero existen adem\u00e1s otros problemas subyacentes m\u00e1s serios relacionados con la higiene. Por eso es imprescindible encontrar la causa y solucionarlo de inmediato.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"%C2%BFQue_causa_el_agua_turbia_en_un_spa\"><\/span>\u00bfQu\u00e9 causa el agua turbia en un spa?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Hay siete causas principales que hacen que el agua se vuelva turbia y que van desde un nivel inadecuado de pH hasta la aparici\u00f3n de algas, entre otras.<\/p>\n<ul>\n<li><strong>Nivel de cloro y de pH inadecuados<\/strong><\/li>\n<\/ul>\n<p>Un desajuste en el pH hace que el cloro libre no sea efectivo y se forme muy poca cloramina. Este desequilibrio, combinado con el cloro, hace que el agua se vea turbia.<\/p>\n<p>El nivel de cloro combinado debe estar por debajo de 0,5 ppm o justo por debajo de 0 ppm y el nivel \u00f3ptimo de pH se sit\u00faa entre 7,2 y 7,6.<\/p>\n<p>El agua con un pH alto (por encima de 7,8) tambi\u00e9n reduce la efectividad del cloro contra las bacterias, lo que afecta a\u00fan m\u00e1s la calidad del agua y aumenta el riesgo de aparici\u00f3n de algas.<\/p>\n<ul>\n<li><strong>Amon\u00edaco<\/strong><\/li>\n<\/ul>\n<p>El amon\u00edaco es uno de los contaminantes m\u00e1s comunes en las piscinas, que se introduce en el agua a trav\u00e9s de las personas o por las condiciones medioambientales. Esta sustancia qu\u00edmica se produce de forma natural y puede introducirse en el agua a trav\u00e9s de fluidos corporales, como el sudor o la orina, las escamas de la piel, o part\u00edculas ambientales tra\u00eddas por el viento o la lluvia, o incluso con los productos para el cuidado de la piel.<\/p>\n<ul>\n<li><strong>Primeras etapas de desarrollo de las algas<\/strong><\/li>\n<\/ul>\n<p>En d\u00edas c\u00e1lidos y soleados las algas se multiplican a gran velocidad. Sus esporas entran en el agua por efecto del viento, la lluvia, adheridas a los trajes de ba\u00f1o o incluso en las herramientas de limpieza. Si no hay una correcta filtraci\u00f3n y recirculaci\u00f3n del agua, o si la piscina tiene un bajo nivel de cloro libre, nitrato o CO2, en entornos c\u00e1lidos las algas comenzar\u00e1n a crecer.<\/p>\n<ul>\n<li><strong>Agua dura (niveles de calcio altos)<\/strong><\/li>\n<\/ul>\n<p>La dureza del calcio (CH) se refiere a la suma de todo el calcio disuelto en el agua. Un valor alto provoca inestabilidad, lo cual influir\u00e1 tambi\u00e9n en el pH y la alcalinidad total (TA). El nivel de CH debe estar en el rango de 100-400 ppm y depende de la temperatura. Por encima de 400 ppm se observar\u00e1 turbidez y se producir\u00e1 incrustaci\u00f3n.<\/p>\n<ul>\n<li><strong>Desajuste alcalino<\/strong><\/li>\n<\/ul>\n<p>El nivel alcalino total debe mantenerse bajo para que el agua se conserve limpia. De lo contrario, se desajustar\u00e1 el pH y se producir\u00e1n incrustaciones.<\/p>\n<ul>\n<li><strong>Filtros defectuosos u obstruidos<\/strong><\/li>\n<\/ul>\n<p>Para evitar que el agua del spa se enturbie o se ensucie, el filtro debe funcionar bien. En el 90% de los casos el agua turbia se debe a fallos en el sistema de filtraci\u00f3n.<\/p>\n<ul>\n<li><strong>Suciedad<\/strong><\/li>\n<\/ul>\n<p>La suciedad procedente del entorno, como hojas, ramas, flores, etc., afectar\u00e1 la calidad del agua, especialmente cuando no se recircula correctamente. Incluso el polvo o el polen pueden acumularse en el filtro y afectar el aspecto del agua.<\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2022\/03\/005_IBERSPA_Roma_ambient-cloudy-2.webp\" alt=\"\" title=\"\"><\/p>\n<h2><span class=\"ez-toc-section\" id=\"Como_evitar_la_formacion_de_agua_turbia\"><\/span>C\u00f3mo evitar la formaci\u00f3n de agua turbia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>B\u00e1sicamente la manera de evitar que se forme agua turbia en un spa pasa por abordar las siete causas mencionadas anteriormente:<\/p>\n<ul>\n<li aria-level=\"1\">Ajustar los niveles de cloro libre<\/li>\n<li aria-level=\"1\">Eliminar el exceso de amon\u00edaco<\/li>\n<li aria-level=\"1\">Eliminar las algas j\u00f3venes<\/li>\n<li aria-level=\"1\">Asegurar un nivel correcto de dureza del calcio<\/li>\n<li aria-level=\"1\">Controlar y ajustar los niveles de pH y AT<\/li>\n<li aria-level=\"1\">Lavar el filtro o sustituir el medio filtrante<\/li>\n<li aria-level=\"1\">Quitar las part\u00edculas externas y los dep\u00f3sitos minerales, cepillar y aspirar la piscina.<\/li>\n<\/ul>\n<p><strong>Primer paso: medir el cloro libre y ajustarlo<\/strong><\/p>\n<p>Dado que una de las causas m\u00e1s comunes del agua turbia es un nivel bajo de cloro libre, lo primero que tenemos que hacer es medir este par\u00e1metro. A continuaci\u00f3n podemos calcular el valor del cloro combinado restando el cloro libre del valor del cloro total. Si el cloro libre est\u00e1 por debajo de 3 ppm, o el cloro combinado est\u00e1 por encima de 0,5 ppm, debemos a\u00f1adir cloro.<\/p>\n<p><strong>Detectar amon\u00edaco y\/o las algas<\/strong><\/p>\n<p>Incluso despu\u00e9s de a\u00f1adir cloro, el nivel de cloro libre no aumentar\u00e1 f\u00e1cilmente. Si despu\u00e9s de a\u00f1adir una gran cantidad de cloro sigue sin subir, es posible que tengamos amon\u00edaco en la piscina.<\/p>\n<p>En ese caso, realizaremos una prueba de p\u00e9rdida de cloro durante la noche, a\u00f1adiendo cloro despu\u00e9s de la puesta de sol y efectuando la lectura de cloro libre por la ma\u00f1ana. Si est\u00e1 por debajo de 1 ppm durante la noche podr\u00eda ser un indicativo de que est\u00e1n empezando a crecer algas.<\/p>\n<p>El amon\u00edaco y las algas aparecen cuando el nivel de cloro libre es insuficiente, as\u00ed que debemos asegurarnos de mantenerlo siempre al nivel adecuado para combatirlos.<\/p>\n<p><strong>Usar un alguicida para limpiar el agua<\/strong><\/p>\n<p>Aunque los alguicidas pueden eliminar las algas j\u00f3venes, la mejor manera de eliminarlas es cepillar y limpiar bien el spa utilizando un recogedor de red, aspirarlo y realizar un tratamiento de cloraci\u00f3n l\u00edquida de choque. Como medida preventiva, el alguicida debe usarse con moderaci\u00f3n. Cuando aparezca un brote, en cambio, ser\u00e1 menos \u00fatil. Podr\u00eda acabar usando una gran cantidad, gastando mucho y obteniendo un peor resultado que con una cloraci\u00f3n de choque.<\/p>\n<p><strong>Corregir el nivel bajo de cloro libre que ha provocado el agua turbia<\/strong><\/p>\n<p>Un nivel bajo de cloro libre tiene varias causas: un uso intensivo, fuertes lluvias, o d\u00edas calurosos y soleados en los que la luz ultravioleta oxida la piscina. El uso de un estabilizador de cloro como el \u00e1cido cian\u00farico evita el desgaste causado por los rayos UV, pero es muy fuerte y har\u00e1 que el cloro libre desaparezca si se sobrepasa el nivel recomendado.<\/p>\n<p>El cloro l\u00edquido o hipoclorito de sodio es la mejor opci\u00f3n para proporcionar un refuerzo diario de cloro libre, ya que no afecta al pH, ni a la dureza del calcio o el nivel de \u00e1cido cian\u00farico en el agua.<\/p>\n<p><strong>Controlar el pH y la alcalinidad total<\/strong><\/p>\n<p>El nivel de pH del agua influye en el funcionamiento de todos los dem\u00e1s productos qu\u00edmicos, por lo que es importante controlarlo. Si el pH es alto el cloro no es efectivo y hace que el agua se vea opaca, as\u00ed que debemos asegurarnos de mantener el pH entre 7,4 y 7,8.<\/p>\n<p>La alcalinidad total debe estar en el rango de 80-120 ppm para que no aumenten el nivel de pH y las incrustaciones de calcio.<\/p>\n<p><strong>Limpiar el sistema de filtraci\u00f3n<\/strong><\/p>\n<p>Una mala circulaci\u00f3n del agua tambi\u00e9n causa problemas, por lo que debemos asegurarnos de que las v\u00e1lvulas de retorno est\u00e9n orientadas hacia abajo para que el agua del spa circule correctamente.<\/p>\n<p>Debemos usar el tama\u00f1o de bomba correcto y asegurarnos de que el sistema de filtraci\u00f3n est\u00e9 en funcionamiento el tiempo suficiente. Hay que retirar cualquier part\u00edcula que bloquee el filtro.<\/p>\n<p><strong>Retirar las part\u00edculas externas y limpiar la piscina en profundidad<\/strong><\/p>\n<p>Podemos usar una red para eliminar las part\u00edculas visibles y un clarificador para limpiar el agua si persiste la turbidez. Para eliminar las part\u00edculas finas, utilizaremos un floculante y despu\u00e9s aspiraremos el spa. Para eliminar las algas, cepillaremos y limpiaremos el spa con un recogedor de red y una aspiradora.<\/p>\n<h2><span class=\"ez-toc-section\" id=\"Mantener_el_spa_libre_de_agua_turbia\"><\/span>Mantener el spa libre de agua turbia<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Si seguimos los consejos anteriores para tratar las diversas causas que forman el agua turbia en un spa ayudaremos a prevenir este fen\u00f3meno. Adem\u00e1s, se pueden implementar varios sistemas y aplicaciones de tratamiento del agua para automatizar algunos de estos procesos y reducir las tareas manuales.<\/p>\n<p>Por ejemplo:<\/p>\n<ul>\n<li aria-level=\"1\"><strong>Freepool2.<\/strong> Una soluci\u00f3n revolucionaria para el tratamiento y la desinfecci\u00f3n de piscinas p\u00fablicas que utiliza Neolysis para desinfectar el agua con luz UV y electr\u00f3lisis de baja salinidad.<\/li>\n<\/ul>\n<ul>\n<li aria-level=\"1\"><strong><a href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/tecnologia-i-sostenibilitat\/neolysis\/\">Neolysis<\/a>:<\/strong> La combinaci\u00f3n de tecnolog\u00eda UV con electr\u00f3lisis de baja salinidad en un solo reactor ha demostrado ser una excelente soluci\u00f3n para el tratamiento y la desinfecci\u00f3n del agua. El sistema Neolysis combina las principales caracter\u00edsticas y beneficios de estas tecnolog\u00edas y corrige sus inconvenientes o limitaciones.<\/li>\n<li aria-level=\"1\"><strong><a href=\"https:\/\/www.fluidra.com\/ca\/solucions-comercials\/tecnologia-i-sostenibilitat\/fluidra-connect\/\">Fluidra Connect.<\/a><\/strong> Una soluci\u00f3n inteligente para supervisar y controlar la piscina de forma remota, con la cual el operador puede activar el sistema de filtraci\u00f3n, tratamiento de agua, iluminaci\u00f3n, sistema de riego, jets de agua, cubiertas y sistemas de calentamiento y deshumidificaci\u00f3n.<\/li>\n<\/ul>\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es el agua turbia? El agua turbia es un t\u00e9rmino que se utiliza para describir el agua que se ve brumosa y ofrece un aspecto desagradable. Por lo general, cuando esto ocurre no se puede ver el fondo de la piscina porque el agua se ha mezclado con muchas part\u00edculas diminutas que reflejan la [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":46738,"template":"","meta":{"_acf_changed":false},"new-category":[2167],"class_list":["post-52804","new","type-new","status-publish","has-post-thumbnail","hentry","new-category-wellness-ca"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/new\/52804","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/new"}],"about":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/types\/new"}],"author":[{"embeddable":true,"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/users\/10"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/media\/46738"}],"wp:attachment":[{"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/media?parent=52804"}],"wp:term":[{"taxonomy":"new-category","embeddable":true,"href":"https:\/\/www.fluidra.com\/ca\/wp-json\/wp\/v2\/new-category?post=52804"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}