{"id":9678,"date":"2025-01-20T16:33:23","date_gmt":"2025-01-20T15:33:23","guid":{"rendered":"https:\/\/www.fluidra.com\/person\/jose-manuel-vargas-gomez\/"},"modified":"2026-03-26T16:00:32","modified_gmt":"2026-03-26T15:00:32","slug":"jose-manuel-vargas-gomez","status":"publish","type":"person","link":"https:\/\/www.fluidra.com\/es\/person\/jose-manuel-vargas-gomez\/","title":{"rendered":"Jos\u00e9 Manuel Vargas G\u00f3mez"},"content":{"rendered":"\n<p>Nacido en 1970, Jos\u00e9 Manuel Vargas se incorpor\u00f3 a Rh\u00f4ne en 2007 como Senior Advisor y pas\u00f3 a ser Director General (Managing Director) en 2017. En abril de 2021, el Sr. Vargas ces\u00f3 temporalmente como Managing Director de la firma y volvi\u00f3 a su funci\u00f3n de Senior Advisor, para dedicar sus esfuerzos a Maxam, una compa\u00f1\u00eda que se encuentra dentro del portfolio de inversiones de Rh\u00f4ne, ya que desde mayo de 2020 asumi\u00f3 el cargo de Presidente Ejecutivo y CEO de Maxam.<\/p>\n\n\n\n<p>Desde el 1 de enero de 2024, el Sr. Vargas retom\u00f3 su funci\u00f3n de Managing Director de Rh\u00f4ne, y ha asumido responsabilidades de supervisi\u00f3n de las operaciones europeas de Rh\u00f4ne desde la oficina de Londres de la firma. Por esta raz\u00f3n dimiti\u00f3 como Consejero Delegado de Maxam y sigue siendo Presidente de la multinacional como parte de la supervisi\u00f3n continua de Rh\u00f4ne de su inversi\u00f3n.<\/p>\n\n\n\n<p>Con anterioridad, ocup\u00f3 el cargo de Presidente y Consejero Delegado de Aena SME, S.A. liderando su reestructuraci\u00f3n, privatizaci\u00f3n parcial y salida a bolsa en 2015. Antes de incorporarse a Aena, ocup\u00f3 puestos de alta direcci\u00f3n en Vocento S.A., donde fue Director Financiero hasta su ascenso a Consejero Delegado y fue tambi\u00e9n Consejero Delegado de ABC. Antes de su paso por el sector de la comunicaci\u00f3n, fue Director Financiero y Secretario General de JOTSA (parte del Grupo Philipp Holzmann).<\/p>\n\n\n\n<p>Adem\u00e1s de su papel como Presidente de Maxam, el Sr. Vargas tambi\u00e9n forma parte del Consejo de Administraci\u00f3n de Fluidra S.A. A lo largo de su carrera, el Sr. Vargas tambi\u00e9n ha formado parte del Consejo de Administraci\u00f3n de otras empresas, como Aena, Vocento, Diario ABC, Cadena COPE, Net TV, Diario El Correo y Wellbore Integrity Solutions.<\/p>\n\n\n\n<p>Desde el inicio de 2024, tambi\u00e9n ha sido nombrado consejero en dos empresas: ASK Chemicals, del portfolio de Rh\u00f4ne, y Petra Diamonds, siendo nombrado Presidente de esta \u00faltima en noviembre de 2024.<\/p>\n\n\n\n<p>En 2015 fue galardonado como \u00abMejor Directivo del A\u00f1o\u00bb por la Asociaci\u00f3n Espa\u00f1ola de Directivos (AED) y reconocido como \u201cPersona del A\u00f1o\u201d dentro del mundo Econ\u00f3mico y Financiero por \u00abEl Economista\u00bb.<\/p>\n\n\n\n<p>El Sr. Vargas es licenciado en Ciencias Econ\u00f3micas y Empresariales por la Universidad Complutense de Madrid y en Derecho por la UNED. Tambi\u00e9n es censor jurado de cuentas.<\/p>\n","protected":false},"featured_media":40487,"template":"","meta":{"_acf_changed":true},"class_list":["post-9678","person","type-person","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/person\/9678","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/person"}],"about":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/types\/person"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/media\/40487"}],"wp:attachment":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/media?parent=9678"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}