{"id":9064,"date":"2025-01-07T17:41:55","date_gmt":"2025-01-07T16:41:55","guid":{"rendered":"https:\/\/www.fluidra.com\/solution\/landscaping-fountains\/"},"modified":"2025-02-28T11:06:20","modified_gmt":"2025-02-28T10:06:20","slug":"fuentes-paisajismo","status":"publish","type":"solution","link":"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-paisajismo\/","title":{"rendered":"Fuentes para paisajismo"},"content":{"rendered":"<div id=\"TopNavTabs-block_e396a3903c7118902f18a7453f60038e\" class=\"TopNavTabs\">\r\n\r\n    <div class=\"container-fluid\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12 px-0\">\r\n                <div class=\"subMenu\">\r\n                                            <div class=\"title\">\r\n                            Soluciones Comerciales                        <\/div>\r\n                                        <div class=\"arrowsMenus\">\r\n                        <button class=\"scroll-button left\">\r\n                            <img decoding=\"async\" alt=\"icon\" class=\"arrow\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/next-icon.svg\" title=\"\">\r\n                        <\/button>\r\n                        <button class=\"scroll-button right\">\r\n                            <img decoding=\"async\" alt=\"icon\" class=\"arrow\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/next-icon.svg\" title=\"\">\r\n                        <\/button>\r\n                        <div class=\"bodyMenu\">\r\n                            <div class=\"containerMenu\">\r\n                                <div class=\"menu\">\r\n                                    <nav class=\"menu-submenu-proyectos-container\"><ul id=\"menu-submenu-proyectos\" class=\"submenu\"><li id=\"menu-item-40669\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40669\"><a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/\">Introducci\u00f3n<\/a><\/li>\n<li id=\"menu-item-38759\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38759\"><a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/\">Inspiraci\u00f3n<\/a><\/li>\n<li id=\"menu-item-38756\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38756\"><a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/\">Soluciones y Sectores<\/a><\/li>\n<li id=\"menu-item-40664\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-40664\"><a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/\">Referencias<\/a><\/li>\n<li id=\"menu-item-38757\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38757\"><a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/modelo-de-negocio\/\">Modelo de Negocio<\/a><\/li>\n<li id=\"menu-item-38758\" class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-38758\"><a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/tecnologia-y-sostenibilidad\/\">Tecnolog\u00eda y sostenibilidad<\/a><\/li>\n<\/ul><\/nav>                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n    <style>\r\n    #TopNavTabs-block_e396a3903c7118902f18a7453f60038e {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #TopNavTabs-block_e396a3903c7118902f18a7453f60038e {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e\" class=\"SolutionsSectors02\">\r\n\r\n    <div class=\"container\">\r\n                <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"title\"><p>Filtra por nuestras <strong>soluciones y sectores<\/strong> para descubrir las instalaciones acu\u00e1ticas que desarrollamos en Fluidra<\/p>\n<\/div>\r\n            <\/div>\r\n        <\/div>\r\n                <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <ul class=\"nav nav-tabs\" id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-types\" role=\"tablist\">\r\n                    <li class=\"nav-item\" role=\"presentation\">\r\n                        <button data-sibling=\"solution\" class=\"nav-link active\" id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-solution-tab\" data-bs-toggle=\"tab\" data-bs-target=\"#SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-solution\" type=\"button\" role=\"tab\" aria-controls=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-solution\" aria-selected=\"true\">\r\n                            Soluciones                        <\/button>\r\n                    <\/li>\r\n                    <li class=\"nav-item\" role=\"presentation\">\r\n                        <button data-sibling=\"sector\" class=\"nav-link \" id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-sector-tab\" data-bs-toggle=\"tab\" data-bs-target=\"#SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-sector\" type=\"button\" role=\"tab\" aria-controls=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-sector\" aria-selected=\"false\">\r\n                            Sectores                        <\/button>\r\n                    <\/li>\r\n                <\/ul>\r\n                <div class=\"tab-content\" id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-TabContent\">\r\n                    <div class=\"tab-pane fade show active\" id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-solution\" role=\"tabpanel\" aria-labelledby=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-solution-tab\">\r\n                        <div class=\"parentContent\">\r\n                            <div class=\"thisHighlights\">\r\n                                <a class=\"highlights\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\">Destacados<\/a>\r\n                            <\/div>\r\n                            <div class=\"categories\">\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/pool-es\/\">\r\n                                        Piscinas                                    <\/a>\r\n                                                                    <a class=\"category active\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/fountains-es\/\">\r\n                                        Fuentes                                    <\/a>\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/wellness-es\/\">\r\n                                        Wellness                                    <\/a>\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/lakes-and-lagoons-es\/\">\r\n                                        Lagos y Lagunas                                    <\/a>\r\n                                                            <\/div>\r\n                            <select class=\"categoriesMobile\">\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/pool-es\/\" >\r\n                                        Piscinas                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/fountains-es\/\" selected>\r\n                                        Fuentes                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/wellness-es\/\" >\r\n                                        Wellness                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/soluciones\/categoria\/lakes-and-lagoons-es\/\" >\r\n                                        Lagos y Lagunas                                    <\/option>\r\n                                                            <\/select>\r\n                        <\/div>\r\n                    <\/div>\r\n                    <div class=\"tab-pane fade \" id=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-sector\" role=\"tabpanel\" aria-labelledby=\"SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e-sector-tab\">\r\n                        <div class=\"parentContent\">\r\n                            <div class=\"thisHighlights\">\r\n                                <a class=\"highlights\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\">Destacados<\/a>\r\n                            <\/div>\r\n                            <div class=\"categories\">\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/events-es\/\">\r\n                                        Eventos                                    <\/a>\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/sports-club-es\/\">\r\n                                        Clubs Deportivos                                    <\/a>\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/real-estate-y-otros\/\">\r\n                                        Real Estate y Otros                                    <\/a>\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/hospitality-es\/\">\r\n                                        Sector Hotelero                                    <\/a>\r\n                                                                    <a class=\"category \" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/public-administration-es\/\">\r\n                                        Administraci\u00f3n Publica                                    <\/a>\r\n                                                            <\/div>\r\n                            <select class=\"categoriesMobile\">\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/events-es\/\" >\r\n                                        Eventos                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/sports-club-es\/\" >\r\n                                        Clubs Deportivos                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/real-estate-y-otros\/\" >\r\n                                        Real Estate y Otros                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/hospitality-es\/\" >\r\n                                        Sector Hotelero                                    <\/option>\r\n                                                                    <option value=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones-y-sectores\/sectores\/categoria\/public-administration-es\/\" >\r\n                                        Administraci\u00f3n Publica                                    <\/option>\r\n                                                            <\/select>\r\n                        <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n                <div class=\"siblingsCont\" data-parent=\"solution\">\r\n                    <div class=\"siblings\">\r\n                        <div class=\"currentPage\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/chevron-down-primary.webp\" title=\"\">\r\n                        <\/div>\r\n                        <div class=\"pagesNav\">\r\n                                                            <a class=\"\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-sector-hostelero\/\" target=\"_self\">\r\n                                    Fuentes para el sector hotelero                                <\/a>\r\n                                                            <a class=\"\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-zonas-residenciales\/\" target=\"_self\">\r\n                                    Fuentes para zonas residenciales                                <\/a>\r\n                                                            <a class=\"\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-centros-comerciales\/\" target=\"_self\">\r\n                                    Fuentes para centros comerciales                                <\/a>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n    #SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #SolutionsSectors02-block_87ff46d7afe4c7286e6f19f9f262230e {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" class=\"ContentImage no-wave v3 \">\r\n\r\n    <!-- DESKTOP -->\r\n\r\n    <div class=\"d-none d-lg-block\">\r\n        <div class=\"container-fluid\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12 col-lg-6 ps-0\">\r\n                                            <div class=\"title normal\"><h1 class=''>Fuentes para Paisajismo<\/h1>\n<\/div>\r\n                    \r\n                                                    <div class=\"imagesCont\">\r\n                                    <div class=\"leftImage\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 661 531\" fill=\"none\">\r\n                                            <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M312.126 3.79503C425.337 17.8765 427.027 57.8889 497.907 112.152C561.564 160.886 653.828 197.815 660.538 270.528C667.437 345.289 595.781 406.515 529.631 455.95C468.5 501.634 393.385 532.968 312.126 530.903C233.072 528.894 159.984 495.436 107.212 445.216C57.2432 397.662 25.0876 343.95 3.0867 270.528C6.22311 209.611 -17.1573 113.041 29.9265 67.1391C81.3895 16.968 165.134 -8.84485 312.126 3.79503Z\" fill=\"url(#pattern0_5767_3916-d-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f)\"\/>\r\n                                            <defs>\r\n                                                <pattern id=\"pattern0_5767_3916-d-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" patternContentUnits=\"objectBoundingBox\" width=\"1\" height=\"1\">\r\n                                                    <use xlink:href=\"#image0_5767_3916-d-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" transform=\"matrix(0.000293919 0 0 0.0003663 -0.101946 0)\"\/>\r\n                                                <\/pattern>\r\n                                                <image id=\"image0_5767_3916-d-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" width=\"4096\" height=\"2730\" xlink:href=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Fuentes_Paisajismo.jpg\" \/>\r\n                                            <\/defs>\r\n                                        <\/svg>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                            <\/div>\r\n\r\n                <div class=\"col-12 col-lg-5 offset-lg-1 pe-0 d-flex flex-column justify-content-between\">\r\n                    <div>\r\n                                                    <div class=\"text normal\"><p><strong>Soluciones ornamentales para enriquecer el paisaje e inspirar a las personas. Se caracterizan por su construcci\u00f3n eficiente y su bajo coste de mantenimiento al emplear productos fabricados por nosotros mismos.<\/strong><\/p>\n<p>Llevamos desde el a\u00f1o 1997 dise\u00f1ando fuentes para paisajes. Por eso, a d\u00eda de hoy contamos con la experiencia y los conocimientos necesarios para desarrollar proyectos de fuentes ornamentales que enriquezen el paisaje. Trabajamos con arquitectos de renombre internacional y ofrecemos dise\u00f1os de fuentes exclusivas y personalizables.<\/p>\n<p>Entre nuestros trabajos m\u00e1s destacados se incluyen las fuentes que hemos creado en lugares tan lejanos como <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/turkistan-i-city-hall-fountains-watershow\/\">Turkistan City Hall Fountains Watershow (Turkist\u00e1n, Kazajist\u00e1n)<\/a> y <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/la-pedrera-park-fountain\/\">La Pedrera Park Fountain (San Lu\u00eds, Argentina)<\/a>. El car\u00e1cter personal y exclusivo de nuestras fuentes se puede palpar, por ejemplo, en los proyectos que llevamos a cabo para la <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/astana-expo-2017\/\">Astana Expo 2017 (Astana, Kazajist\u00e1n)<\/a>, la <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/newcastle-great-exhibition-of-the-north\/\">Newcastle Great Exhibition of the North (Newcastle, Reino Unido)<\/a> y <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/geyser-baku\/\">Geyser Bak\u00fa (Bak\u00fa, Azerbaiy\u00e1n)<\/a>.<\/p>\n<\/div>\r\n                                                                    <\/div>\r\n                                                    <div class=\"imagesCont\">\r\n                                    <div class=\"rightImage\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 508 519\" fill=\"none\">\r\n                                            <path d=\"M194.765 320.391C56.4241 357.459 -26.2755 497.185 9.44862 632.72C46.1859 767.983 187.761 847.614 326.102 810.546C402.364 790.111 461.73 738.668 493.715 673.831C495.885 669.4 497.863 664.626 499.798 660.06C619.268 402.984 752.88 662.53 919.339 702.03C983.272 721.423 1053.6 723.801 1123.33 705.118C1318.5 652.823 1435.22 455.512 1384.59 264.349C1332.93 73.3657 1133.14 -38.9382 937.97 13.3574C868.247 32.0396 808.502 69.1725 762.831 117.934C638.307 235.304 652.485 526.951 420.458 363.959C416.499 360.973 412.423 357.919 408.213 355.099C348.161 314.825 270.96 300.073 194.698 320.508\" stroke=\"#334FAA\" stroke-miterlimit=\"10\"\/>\r\n                                        <\/svg>\r\n                                    <\/div>\r\n                                <\/div>\r\n                                                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"d-block d-lg-none\">\r\n        <div class=\"container\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12 col-lg-6\">\r\n                                            <div class=\"title normal\"><h1 class=''>Fuentes para Paisajismo<\/h1>\n<\/div>\r\n                                    <\/div>\r\n                <div class=\"col-12 col-lg-6\">\r\n                                            <div class=\"text normal\"><p><strong>Soluciones ornamentales para enriquecer el paisaje e inspirar a las personas. Se caracterizan por su construcci\u00f3n eficiente y su bajo coste de mantenimiento al emplear productos fabricados por nosotros mismos.<\/strong><\/p>\n<p>Llevamos desde el a\u00f1o 1997 dise\u00f1ando fuentes para paisajes. Por eso, a d\u00eda de hoy contamos con la experiencia y los conocimientos necesarios para desarrollar proyectos de fuentes ornamentales que enriquezen el paisaje. Trabajamos con arquitectos de renombre internacional y ofrecemos dise\u00f1os de fuentes exclusivas y personalizables.<\/p>\n<p>Entre nuestros trabajos m\u00e1s destacados se incluyen las fuentes que hemos creado en lugares tan lejanos como <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/turkistan-i-city-hall-fountains-watershow\/\">Turkistan City Hall Fountains Watershow (Turkist\u00e1n, Kazajist\u00e1n)<\/a> y <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/la-pedrera-park-fountain\/\">La Pedrera Park Fountain (San Lu\u00eds, Argentina)<\/a>. El car\u00e1cter personal y exclusivo de nuestras fuentes se puede palpar, por ejemplo, en los proyectos que llevamos a cabo para la <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/astana-expo-2017\/\">Astana Expo 2017 (Astana, Kazajist\u00e1n)<\/a>, la <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/newcastle-great-exhibition-of-the-north\/\">Newcastle Great Exhibition of the North (Newcastle, Reino Unido)<\/a> y <a href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/geyser-baku\/\">Geyser Bak\u00fa (Bak\u00fa, Azerbaiy\u00e1n)<\/a>.<\/p>\n<\/div>\r\n                                                        <\/div>\r\n            <\/div>\r\n        <\/div>\r\n\r\n\r\n                            <div class=\"container-fluid imagesCont\">\r\n                        <div class=\"row\">\r\n                            <div class=\"col-12 col-lg-6 ps-0\">\r\n                                                                    <div class=\"leftImage\">\r\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"http:\/\/www.w3.org\/1999\/xlink\" viewBox=\"0 0 661 531\" fill=\"none\">\r\n                                            <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M312.126 3.79503C425.337 17.8765 427.027 57.8889 497.907 112.152C561.564 160.886 653.828 197.815 660.538 270.528C667.437 345.289 595.781 406.515 529.631 455.95C468.5 501.634 393.385 532.968 312.126 530.903C233.072 528.894 159.984 495.436 107.212 445.216C57.2432 397.662 25.0876 343.95 3.0867 270.528C6.22311 209.611 -17.1573 113.041 29.9265 67.1391C81.3895 16.968 165.134 -8.84485 312.126 3.79503Z\" fill=\"url(#pattern0_5767_3916-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f)\"\/>\r\n                                            <defs>\r\n                                                <pattern id=\"pattern0_5767_3916-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" patternContentUnits=\"objectBoundingBox\" width=\"1\" height=\"1\">\r\n                                                    <use xlink:href=\"#image0_5767_3916-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" transform=\"matrix(0.000293919 0 0 0.0003663 -0.101946 0)\"\/>\r\n                                                <\/pattern>\r\n                                                <image id=\"image0_5767_3916-ContentImage-block_62e615fe18abcbaa1258554fcd98da8f\" width=\"4096\" height=\"2730\" xlink:href=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Fuentes_Paisajismo.jpg\" \/>\r\n                                            <\/defs>\r\n                                        <\/svg>\r\n                                    <\/div>\r\n                                                            <\/div>\r\n                            <div class=\"col-12 col-lg-6 pe-0\">\r\n                                <div class=\"rightImage\">\r\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" viewBox=\"0 0 508 579\" fill=\"none\">\r\n                                        <path d=\"M194.765 320.391C56.4241 357.459 -26.2755 497.185 9.44862 632.72C46.1859 767.983 187.761 847.614 326.102 810.546C402.364 790.111 461.73 738.668 493.715 673.831C495.885 669.4 497.863 664.626 499.798 660.06C619.268 402.984 752.88 662.53 919.339 702.03C983.272 721.423 1053.6 723.801 1123.33 705.118C1318.5 652.823 1435.22 455.512 1384.59 264.349C1332.93 73.3657 1133.14 -38.9382 937.97 13.3574C868.247 32.0396 808.502 69.1725 762.831 117.934C638.307 235.304 652.485 526.951 420.458 363.959C416.499 360.973 412.423 357.919 408.213 355.099C348.161 314.825 270.96 300.073 194.698 320.508\" stroke=\"#334FAA\" stroke-miterlimit=\"10\"\/>\r\n                                    <\/svg>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n                    <\/div>\r\n                        <\/div>\r\n\r\n        <style>\r\n    #ContentImage-block_62e615fe18abcbaa1258554fcd98da8f {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #ContentImage-block_62e615fe18abcbaa1258554fcd98da8f {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066\" class=\"ContentRecommendation\" style=\"background-color:#e4f2ff\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12 contElemsSearch\">\r\n                                    <div class=\"title small\" style=\"color:#22377b\"><h2 class=''>Echa un vistazo a nuestros <span style=\"color: #1f7e93;\">ebooks especializados<\/span><\/h2>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"container container-lg-fluid px-3 px-lg-0\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"swiper remove-left-shadow swiperContent\">\r\n                    <div class=\"swiper-wrapper\">\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/ebooks\/ebook-water-fountains-for-hotels-and-shopping-malls\/\" target=\"_blank\">\r\n    <div class=\"ebookCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Portada-Ebook-Fountains-esp-543x768-1.jpg)\"><\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\">Fuentes para Hoteles y Centros Comerciales<\/div>\r\n                <div class=\"arrow\">\r\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n        <\/div>\r\n    <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/ebooks\/ebook-dry-deck-fountain\/\" target=\"_blank\">\r\n    <div class=\"ebookCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Dry-deck-fountains-esp-543x768-1.jpg)\"><\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\">C\u00f3mo elegir el mejor sistema de construcci\u00f3n para fuentes secas<\/div>\r\n                <div class=\"arrow\">\r\n            <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n        <\/div>\r\n    <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"container\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12 d-block\">\r\n                    <div class=\"swiperArrows\">\r\n                        <img loading=\"lazy\" decoding=\"async\" class=\"swiper-prev\" alt=\"icon\" width=\"68\" height=\"66\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/swiper-arrow-primary-hover.svg\" title=\"\">\r\n                        <div class=\"swiper-pagination dark\"><\/div>\r\n                        <img loading=\"lazy\" decoding=\"async\" class=\"swiper-next\" alt=\"icon\" width=\"68\" height=\"66\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/swiper-arrow-primary-hover.svg\" title=\"\">\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 .swiperContent::after { background: linear-gradient(90deg, rgba(228, 242, 255, 0.00) 0%, #e4f2ff 100%); }\r\n        #ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 .swiperContent::before { background: linear-gradient(-90deg, rgba(34, 55, 123, 0.00) 0%, #e4f2ff 100%); }\r\n    <\/style>\r\n    <script>\r\n        jQuery(document).ready(function ($){\r\n            var swiperContent = new Swiper(\"#ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 .swiperContent\", {\r\n                spaceBetween: 26,\r\n                slidesPerView: 'auto',\r\n                pagination: {\r\n                    el: \"#ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 .swiperArrows .swiper-pagination\",\r\n                    clickable: true,\r\n                    enabled: false,\r\n                    dynamicBullets: true,\r\n                    dynamicMainBullets: 5,\r\n                },\r\n                navigation: {\r\n                    nextEl: \"#ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 .swiperArrows .swiper-next\",\r\n                    prevEl: \"#ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 .swiperArrows .swiper-prev\",\r\n                },\r\n                breakpoints: {\r\n                    1024: {\r\n                        pagination: {\r\n                            enabled: true,\r\n                        },\r\n                    },\r\n                    1400: {\r\n                        pagination: {\r\n                            enabled: true,\r\n                        },\r\n                        slidesOffsetBefore: ((window.innerWidth - 1320) \/ 2),\r\n                        slidesOffsetAfter: 20,\r\n                    }\r\n                },\r\n                on: {\r\n                    snapIndexChange: function (swiper){\r\n                        if(swiper.isEnd){\r\n                            $(swiper.el).addClass('remove-right-shadow')\r\n                        } else {\r\n                            $(swiper.el).removeClass('remove-right-shadow')\r\n                        }\r\n                        if(swiper.isBeginning){\r\n                            $(swiper.el).addClass('remove-left-shadow')\r\n                        } else {\r\n                            $(swiper.el).removeClass('remove-left-shadow')\r\n                        }\r\n                    },\r\n                }\r\n            });\r\n        });\r\n    <\/script>\r\n    <style>\r\n    #ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #ContentRecommendation-block_5d1d150c68e13f836053d18f81eb0066 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\n\n<div id=\"InsightBullets-block_25b917e5cff1b5f27450bea1a5af35e4\" class=\"InsightBullets no-wave\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row align-items-center mb-5\">\r\n            <div class=\"col-12 col-lg-6 fullWidth\">\r\n                <div class=\"title\"><h2 class=''>Beneficios de las Fuentes para Paisajismo de Fluidra<\/h2>\n<\/div>\r\n            <\/div>\r\n            <div class=\"col-12 col-lg-6\">\r\n                                                    <div class=\"text\"><p>Nuestra gran experiencia y amplios conocimientos respecto al dise\u00f1o de fuentes con fines paisaj\u00edsticos proporcionan una gran cantidad de beneficios. La emoci\u00f3n y el asombro que estas fuentes despiertan en las personas se deben, entre otras cosas, a que:<\/p>\n<\/div>\r\n                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"cards v01\">\r\n                                                                <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Generates_icon.png\" class=\"image\" alt=\"\" loading=\"lazy\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Genera emociones<\/p>\n<\/div>\r\n                                                                                            <\/div>\r\n                                                    <\/div>\r\n                                                                                        <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Smart-and-automated_icon.png\" class=\"image\" alt=\"\" loading=\"lazy\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Inteligente y automatizada<\/p>\n<\/div>\r\n                                                                                            <\/div>\r\n                                                    <\/div>\r\n                                                                                        <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2024\/09\/Icon-2.svg\" class=\"image\" alt=\"\" loading=\"lazy\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Energ\u00e9ticamentes eficientes<\/p>\n<\/div>\r\n                                                                                            <\/div>\r\n                                                    <\/div>\r\n                                                                                        <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"75\" height=\"75\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Lightweight_icon.png\" class=\"image\" alt=\"\" loading=\"lazy\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>F\u00e1ciles de mantener<\/p>\n<\/div>\r\n                                                                                            <\/div>\r\n                                                    <\/div>\r\n                                                                                        <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"54\" height=\"55\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2024\/10\/premio.webp\" class=\"image\" alt=\"\" loading=\"lazy\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Resistentes y robustas, capaces de soportar los usos m\u00e1s diversos<\/p>\n<\/div>\r\n                                                                                            <\/div>\r\n                                                    <\/div>\r\n                                                                                        <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"54\" height=\"54\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2024\/10\/mano_naturaleza.webp\" class=\"image\" alt=\"\" loading=\"lazy\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Sostenible<\/p>\n<\/div>\r\n                                                                                            <\/div>\r\n                                                    <\/div>\r\n                                                                                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #InsightBullets-block_25b917e5cff1b5f27450bea1a5af35e4 { background: linear-gradient(0deg,  56.56%,  103.88%), #FFF; }\r\n        #InsightBullets-block_25b917e5cff1b5f27450bea1a5af35e4 .cards { grid-template-columns: repeat(4, 1fr); @media screen and (max-width: 1250px){ grid-template-columns: repeat(2, 1fr); }}\r\n    <\/style>\r\n    <style>\r\n    #InsightBullets-block_25b917e5cff1b5f27450bea1a5af35e4 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #InsightBullets-block_25b917e5cff1b5f27450bea1a5af35e4 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"NavigationDropdownsXL-block_c78f1b4f5c0d564ef468cad76048e0d2\" class=\"NavigationDropdownsXL manual\" style=\"background-color:#334faa\">\r\n                    <div class=\"container\">\r\n                        <div class=\"row\">\r\n                            <div class=\"col-12\">\r\n                                                                    <div class=\"title\"><p class=''><span style=\"color: #ffffff;\">Echa un vistazo a nuestro<\/span><br \/>\n<span style=\"color: #ffe366;\">portfolio <\/span><span style=\"color: #ffffff;\">de soluciones<\/span><\/p>\n<\/div>\r\n                                                            <\/div>\r\n                        <\/div>\r\n                        <div class=\"row\">\r\n                            <div class=\"col-12 filters\">\r\n                                                                    <div class=\"tec \" data-text=\"Tecnolog\u00edas de la Construcci\u00f3n\" data-href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-paisajismo\/category\/construction-technologies-es\/\">Tecnolog\u00edas de la Construcci\u00f3n<\/div>\r\n                                                                    <div class=\"tec \" data-text=\"Tecnolog\u00edas para el Tratamiento del Agua y el Aire\" data-href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-paisajismo\/category\/water-environment-es\/\">Tecnolog\u00edas para el Tratamiento del Agua y el Aire<\/div>\r\n                                                                    <div class=\"tec \" data-text=\"Accesorios especiales Tecnolog\u00edas\" data-href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-paisajismo\/category\/special-accesories-es\/\">Accesorios especiales Tecnolog\u00edas<\/div>\r\n                                                                    <div class=\"tec \" data-text=\"Conectividad y Tecnolog\u00edas que crean experiencias\" data-href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-paisajismo\/category\/connectivity-experience-techonologies-es\/\">Conectividad y Tecnolog\u00edas que crean experiencias<\/div>\r\n                                                                    <div class=\"tec \" data-text=\"Tecnolog\u00edas Ornamentales\" data-href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/soluciones\/fuentes-paisajismo\/category\/ornamental-technologies-es\/\">Tecnolog\u00edas Ornamentales<\/div>\r\n                                                            <\/div>\r\n                            <div class=\"col-12\">\r\n                                <div class=\"cards\">\r\n                                                                            <a style=\"display:block;text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/fuentes-secas\/\">\r\n                                            <div class=\"card\" style=\"background-color:#ffffff;color:#22377b\">\r\n                                                <div class=\"cardTitle\">Fuente seca<\/div>\r\n                                                <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/dry-deck-fountains-1.jpg)\">\r\n                                                    <div class=\"arrow\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                <div class=\"excerpt\"><p>Un juego acu\u00e1tico interactivo y multifuncional instalado justo por debajo del nivel del suelo. Produce una serie de chorros que se pueden personalizar para generar din\u00e1micos espect\u00e1culos de agua.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                                        <\/a>\r\n                                                                            <a style=\"display:block;text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/fuentes-de-vaso\/\">\r\n                                            <div class=\"card\" style=\"background-color:#ffffff;color:#22377b\">\r\n                                                <div class=\"cardTitle\">Fuente de vaso<\/div>\r\n                                                <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/vessel-fountains-1-1.jpg)\">\r\n                                                    <div class=\"arrow\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                <div class=\"excerpt\"><p>Los colores, el flujo y el relajante sonido del agua suponen un regalo visual y auditivo para los sentidos al tiempo que consiguen aunar los espacios comunes exteriores e interiores.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                                        <\/a>\r\n                                                                            <a style=\"display:block;text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/reformas-de-piscinas\/\">\r\n                                            <div class=\"card\" style=\"background-color:#ffffff;color:#22377b\">\r\n                                                <div class=\"cardTitle\">Water Show<\/div>\r\n                                                <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/water-show-1-1.jpg)\">\r\n                                                    <div class=\"arrow\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                <div class=\"excerpt\"><p>Una gran puesta en escena de luces y color frente a un fondo de chorros de agua procedentes de la fuente. Resulta impresionante contemplar el extraordinario espect\u00e1culo de agua, luz, sonido, color e incluso fuego.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                                        <\/a>\r\n                                                                            <a style=\"display:block;text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/fuentes-espejo-agua\/\">\r\n                                            <div class=\"card\" style=\"background-color:#ffffff;color:#22377b\">\r\n                                                <div class=\"cardTitle\">Espejo de agua<\/div>\r\n                                                <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/AdobeStock_66563336.jpeg)\">\r\n                                                    <div class=\"arrow\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                <div class=\"excerpt\"><p>Una elegante hoja de agua que a\u00f1ade una refrescante sensaci\u00f3n de esplendor a los espacios p\u00fablicos. La gente se congrega alrededor y queda maravillada ante la armon\u00eda de dise\u00f1o que aporta tanto a jardines como a espacios interiores.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                                        <\/a>\r\n                                                                            <a style=\"display:block;text-decoration: none\" href=\"#\">\r\n                                            <div class=\"card\" style=\"background-color:#ffffff;color:#22377b\">\r\n                                                <div class=\"cardTitle\">G\u00e9iser<\/div>\r\n                                                <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/geiser-1.jpg)\">\r\n                                                    <div class=\"arrow\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                <div class=\"excerpt\"><p>Un enorme chorro de agua que sube disparado hacia el cielo desde un cuerpo de agua ya existente, como una bah\u00eda o un puerto.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                                        <\/a>\r\n                                                                            <a style=\"display:block;text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/fuentes-flotantes-para-jardines\/\">\r\n                                            <div class=\"card\" style=\"background-color:#ffffff;color:#22377b\">\r\n                                                <div class=\"cardTitle\">Fuentes flotantes<\/div>\r\n                                                <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Newcastle-Great-Exhibition-of-the-North_18-2001_cover-1.webp)\">\r\n                                                    <div class=\"arrow\">\r\n                                                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                                    <\/div>\r\n                                                <\/div>\r\n                                                                                                <div class=\"excerpt\"><p>Las fuentes flotantes son estructuras temporales flotantes que se emplazan sobre rios, lagos o el propio mar d\u00f3nde poder instalar espectaculos acu\u00e1ticos, fuentes secas o geysers.<\/p>\n<\/div>\r\n                                            <\/div>\r\n                                        <\/a>\r\n                                                                        <\/div>\r\n                                <\/div>\r\n                            <\/div>\r\n                        <\/div>\r\n    <style>\r\n    #NavigationDropdownsXL-block_c78f1b4f5c0d564ef468cad76048e0d2 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #NavigationDropdownsXL-block_c78f1b4f5c0d564ef468cad76048e0d2 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style>    <style>\r\n        .NavigationDropdownsXL .filters{\r\n            display:flex;\r\n            flex-wrap:wrap;\r\n            gap:8px;\r\n            padding-bottom:40px;\r\n        }\r\n        .NavigationDropdownsXL .filters .tec{\r\n            background-color:#E4F2FF;\r\n            padding:12px 10px;\r\n            border-radius:12px;\r\n            cursor:pointer;\r\n            line-height: 20px;\r\n            text-align:center;\r\n            position: relative;\r\n            display: inline-block;\r\n        }\r\n        .NavigationDropdownsXL .filters .tec.active{\r\n            font-weight: 700;\r\n            font-size: 16px;\r\n            letter-spacing: -2%;\r\n            background-color:#FFE366;\r\n        }\r\n        .tec::after {\r\n            content: attr(data-text);\r\n            font-weight: 700;\r\n            visibility: hidden;\r\n            height: 0;\r\n            display: block;\r\n            overflow: hidden;\r\n        }\r\n    <\/style>\r\n<\/div>\r\n\n\n<div id=\"InsightBullets-block_5d4339e9452b2a595cfe94a3fb7f571c\" class=\"InsightBullets no-wave\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row align-items-center mb-5\">\r\n            <div class=\"col-12 col-lg-6 fullWidth\">\r\n                <div class=\"title\"><h2 class=''>Tecnolog\u00edas relacionadas<\/h2>\n<\/div>\r\n            <\/div>\r\n            <div class=\"col-12 col-lg-6\">\r\n                                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                                    <div class=\"sectionTitle  unsetBottom\"><p><span style=\"color: #2bb4d3;\">Tecnolog\u00edas<\/span> para el Tratamiento del Agua y el Aire<\/p>\n<\/div>\r\n                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"cards v03\">\r\n                                                            <a style=\"text-decoration: none;\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/tecnologia-y-sostenibilidad\/filtrado-y-recirculaciones-eficientes\/\">\r\n                                                <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"450\" height=\"300\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Filtration-praga-filters-room.webp\" class=\"image\" alt=\"Filtrado y recirculaci\u00f3n eficientes\" loading=\"lazy\" srcset=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Filtration-praga-filters-room.webp 450w, https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Filtration-praga-filters-room-300x200.webp 300w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Filtrado y recirculaci\u00f3n eficientes<\/p><\/div>\r\n                                                                                                    <div class=\"cardText\"><p>Eficiencia y sostenibilidad para una piscina limpia y en perfecto funcionamiento.<\/p><\/div>\r\n                                                            <\/div>\r\n                                                            <div class=\"arrow\">\r\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                <\/div>\r\n                                                    <\/div>\r\n                                                    <\/a>\r\n                                                                                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #InsightBullets-block_5d4339e9452b2a595cfe94a3fb7f571c { background: linear-gradient(0deg, rgb(209,230,255) 56.56%, rgb(209,230,255) 103.88%), #FFF; }\r\n        #InsightBullets-block_5d4339e9452b2a595cfe94a3fb7f571c .cards { grid-template-columns: repeat(3, 1fr); @media screen and (max-width: 1250px){ grid-template-columns: repeat(2, 1fr); }}\r\n    <\/style>\r\n    <style>\r\n    #InsightBullets-block_5d4339e9452b2a595cfe94a3fb7f571c {\r\n        margin-top:0px;\r\n        margin-bottom:0px;\r\n        padding-top:92px;\r\n        padding-bottom:92px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #InsightBullets-block_5d4339e9452b2a595cfe94a3fb7f571c {\r\n        margin-top:0px;\r\n        margin-bottom:0px;\r\n        padding-top:0px;\r\n        padding-bottom:0px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"InsightBullets-block_a952c1354888895df5d068e8addeee2a\" class=\"InsightBullets no-wave\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row align-items-center mb-5\">\r\n            <div class=\"col-12 col-lg-6 empty\">\r\n                <div class=\"title\"><\/div>\r\n            <\/div>\r\n            <div class=\"col-12 col-lg-6\">\r\n                                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                                    <div class=\"sectionTitle  unsetBottom\"><p><span style=\"color: #2bb4d6;\">Accesorios<\/span> especiales Tecnolog\u00edas<\/p>\n<\/div>\r\n                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"cards v03\">\r\n                                                            <a style=\"text-decoration: none;\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/tecnologia-y-sostenibilidad\/luz-led\/\">\r\n                                                <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"640\" height=\"338\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Astana-LED-Lighting.webp\" class=\"image\" alt=\"Luz LED\" loading=\"lazy\" srcset=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Astana-LED-Lighting.webp 730w, https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Astana-LED-Lighting-300x158.webp 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Luz LED<\/p><\/div>\r\n                                                                                                    <div class=\"cardText\"><p>La soluci\u00f3n acu\u00e1tica sostenible para una iluminaci\u00f3n excepcional.<\/p><\/div>\r\n                                                            <\/div>\r\n                                                            <div class=\"arrow\">\r\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                <\/div>\r\n                                                    <\/div>\r\n                                                    <\/a>\r\n                                                                                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #InsightBullets-block_a952c1354888895df5d068e8addeee2a { background: linear-gradient(0deg, rgb(209,230,255) 56.56%, rgb(209,230,255) 103.88%), #FFF; }\r\n        #InsightBullets-block_a952c1354888895df5d068e8addeee2a .cards { grid-template-columns: repeat(3, 1fr); @media screen and (max-width: 1250px){ grid-template-columns: repeat(2, 1fr); }}\r\n    <\/style>\r\n    <style>\r\n    #InsightBullets-block_a952c1354888895df5d068e8addeee2a {\r\n        margin-top:0px;\r\n        margin-bottom:0px;\r\n        padding-top:0px;\r\n        padding-bottom:92px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #InsightBullets-block_a952c1354888895df5d068e8addeee2a {\r\n        margin-top:0px;\r\n        margin-bottom:0px;\r\n        padding-top:0px;\r\n        padding-bottom:0px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"InsightBullets-block_f528f090d8ed78f78e246a9a3cfea3a2\" class=\"InsightBullets no-wave\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row align-items-center mb-5\">\r\n            <div class=\"col-12 col-lg-6 empty\">\r\n                <div class=\"title\"><\/div>\r\n            <\/div>\r\n            <div class=\"col-12 col-lg-6\">\r\n                                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                                    <div class=\"sectionTitle  unsetBottom\"><p><span style=\"color: #2bb4d6;\">Tecnolog\u00edas<\/span> Ornamentales<\/p>\n<\/div>\r\n                            <\/div>\r\n        <\/div>\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"cards v03\">\r\n                                                            <a style=\"text-decoration: none;\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/tecnologia-y-sostenibilidad\/coreografia-artistica\/\">\r\n                                                <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"640\" height=\"342\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Artistic-Choreographies-Newcastle.webp\" class=\"image\" alt=\"Coreograf\u00eda art\u00edstica\" loading=\"lazy\" srcset=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Artistic-Choreographies-Newcastle.webp 730w, https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Artistic-Choreographies-Newcastle-300x160.webp 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Coreograf\u00eda art\u00edstica<\/p><\/div>\r\n                                                                                                    <div class=\"cardText\"><p>La combinaci\u00f3n de agua, luz y m\u00fasica permite recrear espect\u00e1culos e historias \u00fanicas.<\/p><\/div>\r\n                                                            <\/div>\r\n                                                            <div class=\"arrow\">\r\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                <\/div>\r\n                                                    <\/div>\r\n                                                    <\/a>\r\n                                                                                    <a style=\"text-decoration: none;\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/tecnologia-y-sostenibilidad\/interactividad\/\">\r\n                                                <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"640\" height=\"437\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Sant-Adria-Interactivity-Funsquare.webp\" class=\"image\" alt=\"Interactividad\" loading=\"lazy\" srcset=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Sant-Adria-Interactivity-Funsquare.webp 730w, https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Sant-Adria-Interactivity-Funsquare-300x205.webp 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Interactividad<\/p><\/div>\r\n                                                                                                    <div class=\"cardText\"><p>Conecte a las personas con el agua mediante fuentes interactivas y espect\u00e1culos acu\u00e1ticos.<\/p><\/div>\r\n                                                            <\/div>\r\n                                                            <div class=\"arrow\">\r\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                <\/div>\r\n                                                    <\/div>\r\n                                                    <\/a>\r\n                                                                                    <a style=\"text-decoration: none;\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/tecnologia-y-sostenibilidad\/fuentes-dinamicas\/\">\r\n                                                <div class=\"cardContent \">\r\n                                                            <img decoding=\"async\" width=\"640\" height=\"360\" src=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Harbor-Dynamic-Fountains.jpg\" class=\"image\" alt=\"Fuentes din\u00e1micas\" loading=\"lazy\" srcset=\"https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Harbor-Dynamic-Fountains.jpg 730w, https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/01\/Harbor-Dynamic-Fountains-300x169.jpg 300w\" sizes=\"auto, (max-width: 640px) 100vw, 640px\" title=\"\">                                                        <div class=\"texts\">\r\n                                                                    <div class=\"cardTitle\"><p>Fuentes din\u00e1micas<\/p><\/div>\r\n                                                                                                    <div class=\"cardText\"><p>Personaliza tu fuente con las \u00faltimas innovaciones en jets de agua, coreograf\u00edas e iluminaci\u00f3n.<\/p><\/div>\r\n                                                            <\/div>\r\n                                                            <div class=\"arrow\">\r\n                                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                                <\/div>\r\n                                                    <\/div>\r\n                                                    <\/a>\r\n                                                                                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #InsightBullets-block_f528f090d8ed78f78e246a9a3cfea3a2 { background: linear-gradient(0deg, rgb(209,230,255) 56.56%, rgb(209,230,255) 103.88%), #FFF; }\r\n        #InsightBullets-block_f528f090d8ed78f78e246a9a3cfea3a2 .cards { grid-template-columns: repeat(3, 1fr); @media screen and (max-width: 1250px){ grid-template-columns: repeat(2, 1fr); }}\r\n    <\/style>\r\n    <style>\r\n    #InsightBullets-block_f528f090d8ed78f78e246a9a3cfea3a2 {\r\n        margin-top:px;\r\n        margin-bottom:0px;\r\n        padding-top:0px;\r\n        padding-bottom:150px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #InsightBullets-block_f528f090d8ed78f78e246a9a3cfea3a2 {\r\n        margin-top:px;\r\n        margin-bottom:0px;\r\n        padding-top:0px;\r\n        padding-bottom:80px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n\n\n<div id=\"ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3\" class=\"ContentRecommendation\" style=\"background-color:#22377b\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12 contElemsSearch\">\r\n                                    <div class=\"title small\" style=\"color:#ffffff\"><h2 class=''>Descubre nuestros<span style=\"color: #ffd100;\"> art\u00edculos<\/span> especializados<\/h2>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"container container-lg-fluid px-3 px-lg-0\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"swiper remove-left-shadow swiperContent\">\r\n                    <div class=\"swiper-wrapper\">\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/ozono-en-piscinas\/\">\r\n    <div class=\"newCard\" style=\"background-color: rgba(255,255,255,0)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2026\/05\/ozone-in-swimming-pools-2-scaled.jpg)\">\r\n                <div class=\"arrow\">\r\n                    <img loading=\"lazy\" decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" width=\"33\" height=\"29\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                                    <div class=\"cardTitle\" style=\"color: rgb(255,255,255)\">Ozono en piscinas: c\u00f3mo funciona y por qu\u00e9 lo eligen los proyectos m\u00e1s avanzados<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(255,255,255)\">\u00bfQu\u00e9 es el ozono y qu\u00e9 papel cumple en el tratamiento del agua? El ozono (O\u2083) es una forma alotr\u00f3pica del ox\u00edgeno compuesta por tres \u00e1tomos y uno de los oxidantes m\u00e1s potentes que se utilizan en el tratamiento del agua. En el contexto de las piscinas, se emplea para oxidar materia org\u00e1nica, inactivar microorganismos [&hellip;]<\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/piscinas-de-hormigon-2\/\">\r\n    <div class=\"newCard\" style=\"background-color: rgba(255,255,255,0)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2026\/05\/piscina-f3_gran-1.jpg)\">\r\n                <div class=\"arrow\">\r\n                    <img loading=\"lazy\" decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" width=\"33\" height=\"29\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                                    <div class=\"cardTitle\" style=\"color: rgb(255,255,255)\">Piscinas de hormig\u00f3n: gu\u00eda completa de tipos, construcci\u00f3n y costes<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(255,255,255)\">\u00bfQu\u00e9 son las piscinas de hormig\u00f3n y por qu\u00e9 elegirlas? Las piscinas de hormig\u00f3n son estructuras permanentes construidas in-situ o con paneles prefabricados de hormig\u00f3n armado, ofreciendo m\u00e1xima personalizaci\u00f3n en forma, tama\u00f1o y acabados. A diferencia de piscinas prefabricadas de poli\u00e9ster o desmontables, el hormig\u00f3n se construye espec\u00edficamente para cada proyecto, adapt\u00e1ndose a terrenos complejos [&hellip;]<\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/proyecto-de-piscina-2\/\">\r\n    <div class=\"newCard\" style=\"background-color: rgba(255,255,255,0)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2026\/05\/Other_092012_IMPERIALGREY-1.jpg-1.jpg)\">\r\n                <div class=\"arrow\">\r\n                    <img loading=\"lazy\" decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" width=\"33\" height=\"29\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                                    <div class=\"cardTitle\" style=\"color: rgb(255,255,255)\">\u00bfC\u00f3mo planificar un proyecto de piscina que garantice durabilidad y eficiencia?<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(255,255,255)\">\u00bfPor d\u00f3nde empieza un buen proyecto de piscina? Todo proyecto de piscina parte de tres preguntas fundamentales: qui\u00e9n va a usar la instalaci\u00f3n, con qu\u00e9 finalidad y en qu\u00e9 condiciones. Definir el uso previsto es el primer paso. No es lo mismo dise\u00f1ar una piscina para una familia que busca ocio y relajaci\u00f3n, que planificar [&hellip;]<\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/mejor-tratamiento-piscinas\/\">\r\n    <div class=\"newCard\" style=\"background-color: rgba(255,255,255,0)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2026\/03\/mejor-tratamiento-para-piscinas.jpg)\">\r\n                <div class=\"arrow\">\r\n                    <img loading=\"lazy\" decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" width=\"33\" height=\"29\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                                    <div class=\"cardTitle\" style=\"color: rgb(255,255,255)\">Mejor tratamiento para piscinas: gu\u00eda completa para elegir con criterio profesional<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(255,255,255)\">El tratamiento del agua de una piscina no se reduce a echar cloro y esperar. Es un sistema: desinfecci\u00f3n, control del pH, floculaci\u00f3n, estabilizaci\u00f3n y, cada vez m\u00e1s, automatizaci\u00f3n de todos esos procesos para que el agua se mantenga en equilibrio sin intervenci\u00f3n constante. Cuando alguien busca el mejor tratamiento de agua para piscinas, la [&hellip;]<\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/como-elegir-mejores-cloradores-salinos\/\">\r\n    <div class=\"newCard\" style=\"background-color: rgba(255,255,255,0)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2026\/03\/cloradores-salados-piscina.jpg)\">\r\n                <div class=\"arrow\">\r\n                    <img loading=\"lazy\" decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" width=\"33\" height=\"29\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                                    <div class=\"cardTitle\" style=\"color: rgb(255,255,255)\">Aprende a elegir los mejores cloradores salinos para tu piscina<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(255,255,255)\">La electr\u00f3lisis salina es hoy el sistema de desinfecci\u00f3n m\u00e1s extendido en piscinas nuevas: genera cloro de forma continua a partir de la sal disuelta en el agua, elimina la manipulaci\u00f3n de productos qu\u00edmicos s\u00f3lidos o l\u00edquidos y, cuando est\u00e1 bien dimensionada, mantiene el agua en equilibrio con un mantenimiento m\u00ednimo. Cuando alguien busca los [&hellip;]<\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/inspiracion\/blog\/tipos-de-filtros-para-piscinas\/\">\r\n    <div class=\"newCard\" style=\"background-color: rgba(255,255,255,0)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2026\/03\/mejor-filtro-para-piscinas.jpg)\">\r\n                <div class=\"arrow\">\r\n                    <img loading=\"lazy\" decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" width=\"33\" height=\"29\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                                    <div class=\"cardTitle\" style=\"color: rgb(255,255,255)\">Tipos de filtros para piscinas y c\u00f3mo elegir el mejor seg\u00fan tu piscina<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(255,255,255)\">El filtro es el aut\u00e9ntico motor de la calidad del agua: si est\u00e1 bien elegido, el agua se mantiene clara, la qu\u00edmica cuadra y el mantenimiento se reduce al m\u00ednimo. Si est\u00e1 mal dimensionado o es el tipo equivocado para tu instalaci\u00f3n, aparecen s\u00edntomas como turbidez persistente, consumo excesivo de productos y una filtraci\u00f3n que [&hellip;]<\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"container\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12 d-block\">\r\n                    <div class=\"swiperArrows\">\r\n                        <img loading=\"lazy\" decoding=\"async\" class=\"swiper-prev\" alt=\"icon\" width=\"68\" height=\"66\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/swiper-arrow-primary-hover.svg\" title=\"\">\r\n                        <div class=\"swiper-pagination light\"><\/div>\r\n                        <img loading=\"lazy\" decoding=\"async\" class=\"swiper-next\" alt=\"icon\" width=\"68\" height=\"66\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/swiper-arrow-primary-hover.svg\" title=\"\">\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 .swiperContent::after { background: linear-gradient(90deg, rgba(228, 242, 255, 0.00) 0%, #22377b 100%); }\r\n        #ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 .swiperContent::before { background: linear-gradient(-90deg, rgba(34, 55, 123, 0.00) 0%, #22377b 100%); }\r\n    <\/style>\r\n    <script>\r\n        jQuery(document).ready(function ($){\r\n            var swiperContent = new Swiper(\"#ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 .swiperContent\", {\r\n                spaceBetween: 26,\r\n                slidesPerView: 'auto',\r\n                pagination: {\r\n                    el: \"#ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 .swiperArrows .swiper-pagination\",\r\n                    clickable: true,\r\n                    enabled: false,\r\n                    dynamicBullets: true,\r\n                    dynamicMainBullets: 5,\r\n                },\r\n                navigation: {\r\n                    nextEl: \"#ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 .swiperArrows .swiper-next\",\r\n                    prevEl: \"#ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 .swiperArrows .swiper-prev\",\r\n                },\r\n                breakpoints: {\r\n                    1024: {\r\n                        pagination: {\r\n                            enabled: true,\r\n                        },\r\n                    },\r\n                    1400: {\r\n                        pagination: {\r\n                            enabled: true,\r\n                        },\r\n                        slidesOffsetBefore: ((window.innerWidth - 1320) \/ 2),\r\n                        slidesOffsetAfter: 20,\r\n                    }\r\n                },\r\n                on: {\r\n                    snapIndexChange: function (swiper){\r\n                        if(swiper.isEnd){\r\n                            $(swiper.el).addClass('remove-right-shadow')\r\n                        } else {\r\n                            $(swiper.el).removeClass('remove-right-shadow')\r\n                        }\r\n                        if(swiper.isBeginning){\r\n                            $(swiper.el).addClass('remove-left-shadow')\r\n                        } else {\r\n                            $(swiper.el).removeClass('remove-left-shadow')\r\n                        }\r\n                    },\r\n                }\r\n            });\r\n        });\r\n    <\/script>\r\n    <style>\r\n    #ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #ContentRecommendation-block_4e6dde0cb32f903c539be97e3640fae3 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\n\n<div id=\"ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381\" class=\"ContentRecommendation\" style=\"background-color:#e4f2ff\">\r\n\r\n    <div class=\"container\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12 contElemsSearch\">\r\n                                    <div class=\"title normal\" style=\"color:#22377b\"><h2 class=''>Una selecci\u00f3n<br \/>\nde nuestros<span style=\"color: #1f7e93;\"> proyectos<\/span><\/h2>\n<\/div>\r\n                                            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"container container-lg-fluid px-3 px-lg-0\">\r\n        <div class=\"row\">\r\n            <div class=\"col-12\">\r\n                <div class=\"swiper remove-left-shadow swiperContent\">\r\n                    <div class=\"swiper-wrapper\">\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/floating-fountain-complex-in-shymkent-city\/\">\r\n    <div class=\"projectCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/07\/Floating-Fountain-Complex-in-Shymkent-City_DJI_0731-scaled.jpg)\">\r\n                                <div class=\"arrow\">\r\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                            <div class=\"tags\">\r\n                                    <div class=\"tag\">PUBLIC ADMINISTRATION<\/div>\r\n                                        <div class=\"tag\">FOUNTAINS<\/div>\r\n                                <\/div>\r\n                            <div class=\"cardTitle\" style=\"color: rgb(34,55,123)\">Floating Fountain Complex in Shymkent City<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\"><\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/hotel-coral-playa-mujeres\/\">\r\n    <div class=\"projectCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/2025\/10\/Hidrobalear-Fountain-Mexico_Hidrobalear-fountain-Mexico-_2_-scaled.jpeg)\">\r\n                                <div class=\"arrow\">\r\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                            <div class=\"tags\">\r\n                                    <div class=\"tag\">HOSPITALITY<\/div>\r\n                                        <div class=\"tag\">FOUNTAINS<\/div>\r\n                                <\/div>\r\n                            <div class=\"cardTitle\" style=\"color: rgb(34,55,123)\">Hotel Coral Playa Mujeres<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\"><\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/font-dels-colors\/\">\r\n    <div class=\"projectCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/references\/22033\/jc_20230705_DSC00377.jpg)\">\r\n                                <div class=\"arrow\">\r\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                            <div class=\"tags\">\r\n                                    <div class=\"tag\">PUBLIC ADMINISTRATION<\/div>\r\n                                        <div class=\"tag\">FOUNTAINS<\/div>\r\n                                <\/div>\r\n                            <div class=\"cardTitle\" style=\"color: rgb(34,55,123)\">Font dels Colors<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\"><\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/astana-central-mosque\/\">\r\n    <div class=\"projectCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/references\/21779\/20220703_120935-scaled.jpg)\">\r\n                                <div class=\"arrow\">\r\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                            <div class=\"tags\">\r\n                                    <div class=\"tag\">PUBLIC ADMINISTRATION<\/div>\r\n                                        <div class=\"tag\">FOUNTAINS<\/div>\r\n                                <\/div>\r\n                            <div class=\"cardTitle\" style=\"color: rgb(34,55,123)\">Astana Central Mosque<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\"><\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/astana-expo-2017\/\">\r\n    <div class=\"projectCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/references\/12105\/17-1003_Cover-scaled.jpg)\">\r\n                                <div class=\"arrow\">\r\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                            <div class=\"tags\">\r\n                                    <div class=\"tag\">PUBLIC ADMINISTRATION<\/div>\r\n                                        <div class=\"tag\">FOUNTAINS<\/div>\r\n                                <\/div>\r\n                            <div class=\"cardTitle\" style=\"color: rgb(34,55,123)\">Astana Expo 2017<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\"><\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                                <div class=\"swiper-slide\">\r\n                            <a style=\"text-decoration: none\" href=\"https:\/\/www.fluidra.com\/es\/soluciones-comerciales\/referencias\/espana-industrial-park\/\">\r\n    <div class=\"projectCard\" style=\"background-color: rgb(255,255,255)\">\r\n                    <div class=\"imageContainer\" style=\"background-image:url(https:\/\/www.fluidra.com\/wp-content\/uploads\/references\/6853\/10-0059_cover-scaled.jpg)\">\r\n                                <div class=\"arrow\">\r\n                    <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/right-arrow-primary.webp\" title=\"\">\r\n                <\/div>\r\n            <\/div>\r\n                            <div class=\"tags\">\r\n                                    <div class=\"tag\">PUBLIC ADMINISTRATION<\/div>\r\n                                        <div class=\"tag\">FOUNTAINS<\/div>\r\n                                <\/div>\r\n                            <div class=\"cardTitle\" style=\"color: rgb(34,55,123)\">Espa\u00f1a Industrial Park<\/div>\r\n                            <div class=\"cardText\" style=\"color: rgb(34,55,123)\"><\/div>\r\n            <\/div>\r\n<\/a>\r\n                        <\/div>\r\n                                            <\/div>\r\n                <\/div>\r\n            <\/div>\r\n        <\/div>\r\n    <\/div>\r\n\r\n    <div class=\"container\">\r\n            <div class=\"row\">\r\n                <div class=\"col-12 d-block\">\r\n                    <div class=\"swiperArrows\">\r\n                        <img loading=\"lazy\" decoding=\"async\" class=\"swiper-prev\" alt=\"icon\" width=\"68\" height=\"66\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/swiper-arrow-primary-hover.svg\" title=\"\">\r\n                        <div class=\"swiper-pagination light\"><\/div>\r\n                        <img loading=\"lazy\" decoding=\"async\" class=\"swiper-next\" alt=\"icon\" width=\"68\" height=\"66\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/swiper-arrow-primary-hover.svg\" title=\"\">\r\n                    <\/div>\r\n                <\/div>\r\n            <\/div>\r\n    <\/div>\r\n\r\n    <style>\r\n        #ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 .swiperContent::after { background: linear-gradient(90deg, rgba(228, 242, 255, 0.00) 0%, #e4f2ff 100%); }\r\n        #ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 .swiperContent::before { background: linear-gradient(-90deg, rgba(34, 55, 123, 0.00) 0%, #e4f2ff 100%); }\r\n    <\/style>\r\n    <script>\r\n        jQuery(document).ready(function ($){\r\n            var swiperContent = new Swiper(\"#ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 .swiperContent\", {\r\n                spaceBetween: 26,\r\n                slidesPerView: 'auto',\r\n                pagination: {\r\n                    el: \"#ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 .swiperArrows .swiper-pagination\",\r\n                    clickable: true,\r\n                    enabled: false,\r\n                    dynamicBullets: true,\r\n                    dynamicMainBullets: 5,\r\n                },\r\n                navigation: {\r\n                    nextEl: \"#ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 .swiperArrows .swiper-next\",\r\n                    prevEl: \"#ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 .swiperArrows .swiper-prev\",\r\n                },\r\n                breakpoints: {\r\n                    1024: {\r\n                        pagination: {\r\n                            enabled: true,\r\n                        },\r\n                    },\r\n                    1400: {\r\n                        pagination: {\r\n                            enabled: true,\r\n                        },\r\n                        slidesOffsetBefore: ((window.innerWidth - 1320) \/ 2),\r\n                        slidesOffsetAfter: 20,\r\n                    }\r\n                },\r\n                on: {\r\n                    snapIndexChange: function (swiper){\r\n                        if(swiper.isEnd){\r\n                            $(swiper.el).addClass('remove-right-shadow')\r\n                        } else {\r\n                            $(swiper.el).removeClass('remove-right-shadow')\r\n                        }\r\n                        if(swiper.isBeginning){\r\n                            $(swiper.el).addClass('remove-left-shadow')\r\n                        } else {\r\n                            $(swiper.el).removeClass('remove-left-shadow')\r\n                        }\r\n                    },\r\n                }\r\n            });\r\n        });\r\n    <\/script>\r\n    <style>\r\n    #ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #ContentRecommendation-block_cbb32e768bfc5e9a70315a48cf94a381 {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\n\n<div id=\"ContactForm-block_9871c569364b433b633f07bb0090567f\" class=\"ContactForm\">\r\n    <div class=\"overflow\"><\/div>\r\n    <div class=\"contactTrigger\">\r\n        <img decoding=\"async\" alt=\"icon\" class=\"openContact\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/chat.webp\" title=\"\">\r\n        <span>Contacto<\/span>\r\n    <\/div>\r\n\r\n    <div class=\"formContainer\">\r\n        <div class=\"closeTrigger\">\r\n            <img decoding=\"async\" alt=\"icon\" class=\"closeContact\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/close-form-primary.webp\" title=\"\">\r\n            <span>Cerrar<\/span>\r\n        <\/div>\r\n        <div class=\"form\">\r\n            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f7915-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"7915\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/solution\/9064#wpcf7-f7915-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"7915\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f7915-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<input class=\"wpcf7-form-control wpcf7-hidden\" value=\"Commercials Solutions - Contact\" type=\"hidden\" name=\"your-subject\" \/>\n<div class=\"top\">\n\t<div class=\"topTitle\">\n\t\t<p>\u00bfTiene alguna pregunta? Rellene el formulario y p\u00f3ngase en contacto con uno de nuestros expertos\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"text\">\n\t\t<p>Nuestro equipo est\u00e1 especializado en la prestaci\u00f3n de servicios de asesoramiento y apoyo para el desarrollo de proyectos acu\u00e1ticos en diferentes sectores.\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"text2\">\n\t<p><b>Todos los campos marcados con * son obligatorios.<\/b> Necesitamos esta informaci\u00f3n para garantizar la mejor experiencia durante el servicio\n\t<\/p>\n<\/div>\n<div class=\"part\">\n\t<div class=\"title\">\n\t\t<p>En primer lugar, necesitamos informaci\u00f3n general sobre usted y sobre c\u00f3mo podemos ponernos en contacto con usted\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"half\">\n\t\t<p><label> Introduzca su nombre *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"first-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Nombre\" value=\"\" type=\"text\" name=\"first-name\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"half\">\n\t\t<p><label> Introduzca su apellido *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"last-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Apellido\" value=\"\" type=\"text\" name=\"last-name\" \/><\/span> <\/label>\n\t\t<\/p>\n\t<\/div>\n\t<div class=\"half\">\n\t\t<p><label> Introduzca su correo electr\u00f3nico profesional*<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" autocomplete=\"email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"email@dominio.com\" value=\"\" type=\"email\" name=\"email\" \/><\/span> <\/label><br \/>\n<label> N\u00famero de tel\u00e9fono<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" autocomplete=\"name\" aria-invalid=\"false\" placeholder=\"600 123 456\" value=\"\" type=\"tel\" name=\"phone\" \/><\/span><br \/>\n<\/label>\n\t\t<\/p>\n\t\t<p class=\"no-mandatory\">Recuerde que este \u00faltimo campo no es obligatorio<br \/>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<div class=\"title\">\n\t<p>Estamos a mitad de camino\n\t<\/p>\n<\/div>\n<div class=\"part\">\n\t<div class=\"title\">\n\t\t<p>H\u00e1blenos de su trabajo\n\t\t<\/p>\n\t<\/div>\n\t<p><label> Introduzca el nombre de su empresa *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Empresa\" value=\"\" type=\"text\" name=\"company\" \/><\/span> <\/label>\n\t<\/p>\n\t<p class=\"label\"> Seleccione su perfil profesional *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"profile\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"profile\" value=\"Arquitectura\" \/><span class=\"wpcf7-list-item-label\">Arquitectura<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"profile\" value=\"Ingenier\u00eda\" \/><span class=\"wpcf7-list-item-label\">Ingenier\u00eda<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"profile\" value=\"Constructor\" \/><span class=\"wpcf7-list-item-label\">Constructor<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"profile\" value=\"Instalador\" \/><span class=\"wpcf7-list-item-label\">Instalador<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"profile\" value=\"Operador\" \/><span class=\"wpcf7-list-item-label\">Operador<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"profile\" value=\"Propietario de instalaci\u00f3n\" \/><span class=\"wpcf7-list-item-label\">Propietario de instalaci\u00f3n<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"profile\" value=\"Estudiante\" \/><span class=\"wpcf7-list-item-label\">Estudiante<\/span><\/label><\/span><span class=\"wpcf7-list-item last has-free-text\"><label><input type=\"radio\" name=\"profile\" value=\"Otro\" \/><span class=\"wpcf7-list-item-label\">Otro<\/span><\/label> <input type=\"text\" name=\"_wpcf7_free_text_profile\" class=\"wpcf7-free-text\" \/><\/span><\/span><\/span>\n\t<\/p>\n\t<p class=\"label\"> Seleccione su posici\u00f3n<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"job_title\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"job_title\" value=\"Arquitecto principal\" \/><span class=\"wpcf7-list-item-label\">Arquitecto principal<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Arquitecto senior\" \/><span class=\"wpcf7-list-item-label\">Arquitecto senior<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Arquitecto junior\" \/><span class=\"wpcf7-list-item-label\">Arquitecto junior<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Ingeniero jefe\" \/><span class=\"wpcf7-list-item-label\">Ingeniero jefe<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Ingeniero senior\" \/><span class=\"wpcf7-list-item-label\">Ingeniero senior<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Ingeniero junior\" \/><span class=\"wpcf7-list-item-label\">Ingeniero junior<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Especialista BIM\" \/><span class=\"wpcf7-list-item-label\">Especialista BIM<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Consultor\" \/><span class=\"wpcf7-list-item-label\">Consultor<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Gerente de la empresa\" \/><span class=\"wpcf7-list-item-label\">Gerente de la empresa<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Gerente de adquisiciones\" \/><span class=\"wpcf7-list-item-label\">Gerente de adquisiciones<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Manager de Proyecto\" \/><span class=\"wpcf7-list-item-label\">Manager de Proyecto<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"job_title\" value=\"Gerente t\u00e9cnico o de mantenimiento\" \/><span class=\"wpcf7-list-item-label\">Gerente t\u00e9cnico o de mantenimiento<\/span><\/label><\/span><span class=\"wpcf7-list-item last has-free-text\"><label><input type=\"radio\" name=\"job_title\" value=\"Otro\" \/><span class=\"wpcf7-list-item-label\">Otro<\/span><\/label> <input type=\"text\" name=\"_wpcf7_free_text_job_title\" class=\"wpcf7-free-text\" \/><\/span><\/span><\/span>\n\t<\/p>\n\t<p class=\"label\"> Pa\u00eds *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"country\"><select class=\"wpcf7-form-control wpcf7-select wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" name=\"country\"><option value=\"\">Seleccione su pa\u00eds<\/option><option value=\"Afghanistan\">Afghanistan<\/option><option value=\"Albania\">Albania<\/option><option value=\"Algeria\">Algeria<\/option><option value=\"Andorra\">Andorra<\/option><option value=\"Angola\">Angola<\/option><option value=\"Anguilla\">Anguilla<\/option><option value=\"Antigua and Barbuda\">Antigua and Barbuda<\/option><option value=\"Argentina\">Argentina<\/option><option value=\"Armenia\">Armenia<\/option><option value=\"Aruba\">Aruba<\/option><option value=\"Australia\">Australia<\/option><option value=\"Austria\">Austria<\/option><option value=\"Azerbaijan\">Azerbaijan<\/option><option value=\"Bahamas\">Bahamas<\/option><option value=\"Bahrain\">Bahrain<\/option><option value=\"Balkans\">Balkans<\/option><option value=\"Bangladesh\">Bangladesh<\/option><option value=\"Barbados\">Barbados<\/option><option value=\"Belarus\">Belarus<\/option><option value=\"Belgium\">Belgium<\/option><option value=\"Belize\">Belize<\/option><option value=\"Benin\">Benin<\/option><option value=\"Bermuda\">Bermuda<\/option><option value=\"Bhutan\">Bhutan<\/option><option value=\"Bolivia\">Bolivia<\/option><option value=\"Bosnia and Herzegovina\">Bosnia and Herzegovina<\/option><option value=\"Botswana\">Botswana<\/option><option value=\"Brazil\">Brazil<\/option><option value=\"British Virgin Islands\">British Virgin Islands<\/option><option value=\"Bulgaria\">Bulgaria<\/option><option value=\"Burkina Faso\">Burkina Faso<\/option><option value=\"Burundi\">Burundi<\/option><option value=\"Cambodia\">Cambodia<\/option><option value=\"Cameroon\">Cameroon<\/option><option value=\"Canada\">Canada<\/option><option value=\"Cape Verde\">Cape Verde<\/option><option value=\"Cayman Islands\">Cayman Islands<\/option><option value=\"Central African Republic\">Central African Republic<\/option><option value=\"Chad\">Chad<\/option><option value=\"Chile\">Chile<\/option><option value=\"China\">China<\/option><option value=\"Colombia\">Colombia<\/option><option value=\"Comoros\">Comoros<\/option><option value=\"Congo (Republic)\">Congo (Republic)<\/option><option value=\"Costa Rica\">Costa Rica<\/option><option value=\"Cote d&#039;Ivoire\">Cote d&#039;Ivoire<\/option><option value=\"Croatia\">Croatia<\/option><option value=\"Cuba\">Cuba<\/option><option value=\"Cyprus\">Cyprus<\/option><option value=\"Czech Republic\">Czech Republic<\/option><option value=\"Democratic Republic of Congo (D. R. C)\">Democratic Republic of Congo (D. R. C)<\/option><option value=\"Denmark\">Denmark<\/option><option value=\"Djibouti\">Djibouti<\/option><option value=\"Dominica\">Dominica<\/option><option value=\"Dominican Republic\">Dominican Republic<\/option><option value=\"Ecuador\">Ecuador<\/option><option value=\"Egypt\">Egypt<\/option><option value=\"El Salvador\">El Salvador<\/option><option value=\"Equatorial Guinea\">Equatorial Guinea<\/option><option value=\"Eritrea\">Eritrea<\/option><option value=\"Ethiopia\">Ethiopia<\/option><option value=\"Federal Democratic Republic of Nepal\">Federal Democratic Republic of Nepal<\/option><option value=\"Fiji\">Fiji<\/option><option value=\"Finland\">Finland<\/option><option value=\"France\">France<\/option><option value=\"French Polynesia\">French Polynesia<\/option><option value=\"Gabon\">Gabon<\/option><option value=\"Gambia\">Gambia<\/option><option value=\"Georgia\">Georgia<\/option><option value=\"Germany\">Germany<\/option><option value=\"Ghana\">Ghana<\/option><option value=\"Gibraltar\">Gibraltar<\/option><option value=\"Greece\">Greece<\/option><option value=\"Grenada\">Grenada<\/option><option value=\"Guatemala\">Guatemala<\/option><option value=\"Guinea\">Guinea<\/option><option value=\"Haiti\">Haiti<\/option><option value=\"Honduras\">Honduras<\/option><option value=\"Hong Kong\">Hong Kong<\/option><option value=\"Hungary\">Hungary<\/option><option value=\"Iceland\">Iceland<\/option><option value=\"India\">India<\/option><option value=\"Indonesia\">Indonesia<\/option><option value=\"Iran\">Iran<\/option><option value=\"Iraq\">Iraq<\/option><option value=\"Ireland\">Ireland<\/option><option value=\"Israel\">Israel<\/option><option value=\"Italy\">Italy<\/option><option value=\"Jamaica\">Jamaica<\/option><option value=\"Japan\">Japan<\/option><option value=\"Jordan\">Jordan<\/option><option value=\"Kazakhstan\">Kazakhstan<\/option><option value=\"Kenya\">Kenya<\/option><option value=\"Kuwait\">Kuwait<\/option><option value=\"Kyrgyzstan\">Kyrgyzstan<\/option><option value=\"Laos\">Laos<\/option><option value=\"Latvia\">Latvia<\/option><option value=\"Lebanon\">Lebanon<\/option><option value=\"Liberia\">Liberia<\/option><option value=\"Libya\">Libya<\/option><option value=\"Liechtenstein\">Liechtenstein<\/option><option value=\"Lithuania\">Lithuania<\/option><option value=\"Macau\">Macau<\/option><option value=\"Macedonia\">Macedonia<\/option><option value=\"Malaysia\">Malaysia<\/option><option value=\"Maldives\">Maldives<\/option><option value=\"Mali\">Mali<\/option><option value=\"Malta\">Malta<\/option><option value=\"Mauritania\">Mauritania<\/option><option value=\"Mauritius\">Mauritius<\/option><option value=\"Mexico\">Mexico<\/option><option value=\"Monaco\">Monaco<\/option><option value=\"Mongolia\">Mongolia<\/option><option value=\"Montenegro\">Montenegro<\/option><option value=\"Morocco\">Morocco<\/option><option value=\"Mozambique\">Mozambique<\/option><option value=\"Myanmar\">Myanmar<\/option><option value=\"Namibia\">Namibia<\/option><option value=\"Netherland Antilles\">Netherland Antilles<\/option><option value=\"Netherlands\">Netherlands<\/option><option value=\"New Caledonia\">New Caledonia<\/option><option value=\"New Zealand\">New Zealand<\/option><option value=\"Nicaragua\">Nicaragua<\/option><option value=\"Niger\">Niger<\/option><option value=\"Nigeria\">Nigeria<\/option><option value=\"North Sudan\">North Sudan<\/option><option value=\"Northern Mariana Islands\">Northern Mariana Islands<\/option><option value=\"Norway\">Norway<\/option><option value=\"Oman\">Oman<\/option><option value=\"Pakistan\">Pakistan<\/option><option value=\"Palau\">Palau<\/option><option value=\"Panama\">Panama<\/option><option value=\"Papua New Guinea\">Papua New Guinea<\/option><option value=\"Paraguay\">Paraguay<\/option><option value=\"Peru\">Peru<\/option><option value=\"Philippines\">Philippines<\/option><option value=\"Poland\">Poland<\/option><option value=\"Portugal\">Portugal<\/option><option value=\"Puerto Rico\">Puerto Rico<\/option><option value=\"Qatar\">Qatar<\/option><option value=\"Romania\">Romania<\/option><option value=\"Russia\">Russia<\/option><option value=\"Rwanda\">Rwanda<\/option><option value=\"Saint-Barth\u00e9lemy\">Saint-Barth\u00e9lemy<\/option><option value=\"Salomon Islands\">Salomon Islands<\/option><option value=\"San Cristobal y Nieves\">San Cristobal y Nieves<\/option><option value=\"Saudi Arabia\">Saudi Arabia<\/option><option value=\"Senegal\">Senegal<\/option><option value=\"Serbia\">Serbia<\/option><option value=\"Seychelles\">Seychelles<\/option><option value=\"Sierra Leone\">Sierra Leone<\/option><option value=\"Singapore\">Singapore<\/option><option value=\"Slovakia\">Slovakia<\/option><option value=\"Slovenia\">Slovenia<\/option><option value=\"Somalia\">Somalia<\/option><option value=\"South Africa\">South Africa<\/option><option value=\"South Korea\">South Korea<\/option><option value=\"South Sudan\">South Sudan<\/option><option value=\"Spain\">Spain<\/option><option value=\"Sri Lanka\">Sri Lanka<\/option><option value=\"St. Kitts and Nevis\">St. Kitts and Nevis<\/option><option value=\"St. Lucia\">St. Lucia<\/option><option value=\"St. Martin\">St. Martin<\/option><option value=\"Surinam\">Surinam<\/option><option value=\"Swaziland\">Swaziland<\/option><option value=\"Sweden\">Sweden<\/option><option value=\"Switzerland\">Switzerland<\/option><option value=\"Syria\">Syria<\/option><option value=\"Taiwan\">Taiwan<\/option><option value=\"Tajikistan\">Tajikistan<\/option><option value=\"Tanzania\">Tanzania<\/option><option value=\"Thailand\">Thailand<\/option><option value=\"Timor-Leste\">Timor-Leste<\/option><option value=\"Togo\">Togo<\/option><option value=\"Trinidad y Tobago\">Trinidad y Tobago<\/option><option value=\"Tunisia\">Tunisia<\/option><option value=\"Turkey\">Turkey<\/option><option value=\"Turks and Caicos Islands\">Turks and Caicos Islands<\/option><option value=\"Uganda\">Uganda<\/option><option value=\"Ukraine\">Ukraine<\/option><option value=\"United Arab Emirates\">United Arab Emirates<\/option><option value=\"United Kingdom\">United Kingdom<\/option><option value=\"United Republic of Tanzania\">United Republic of Tanzania<\/option><option value=\"United States of America\">United States of America<\/option><option value=\"Uruguay\">Uruguay<\/option><option value=\"Uzbekistan\">Uzbekistan<\/option><option value=\"Venezuela\">Venezuela<\/option><option value=\"Vietnam\">Vietnam<\/option><option value=\"Zambia\">Zambia<\/option><option value=\"Zimbabwe\">Zimbabwe<\/option><\/select><\/span>\n\t<\/p>\n\t<p class=\"label\"> Seleccione el alcance t\u00edpico de los proyectos en los que colabora *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"scope\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"scope\" value=\"Proyectos locales\" \/><span class=\"wpcf7-list-item-label\">Proyectos locales<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"scope\" value=\"Proyectos internacionales\" \/><span class=\"wpcf7-list-item-label\">Proyectos internacionales<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"radio\" name=\"scope\" value=\"Ambos\" \/><span class=\"wpcf7-list-item-label\">Ambos<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n<\/div>\n<div class=\"title\">\n\t<p>Ya casi hemos terminado\n\t<\/p>\n<\/div>\n<div class=\"part\">\n\t<div class=\"title\">\n\t\t<p>Nos gustar\u00eda escucharle. \u00bfQu\u00e9 le interesa y qu\u00e9 necesita?\n\t\t<\/p>\n\t<\/div>\n\t<p class=\"with-bullet label\"> Seleccione su sector de inter\u00e9s<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"sector\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"sector[]\" value=\"Hoteler\u00eda\" \/><span class=\"wpcf7-list-item-label\">Hoteler\u00eda<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"sector[]\" value=\"Inmobiliario\" \/><span class=\"wpcf7-list-item-label\">Inmobiliario<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"sector[]\" value=\"Administraci\u00f3n p\u00fablica\" \/><span class=\"wpcf7-list-item-label\">Administraci\u00f3n p\u00fablica<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"sector[]\" value=\"Centros deportivos\" \/><span class=\"wpcf7-list-item-label\">Centros deportivos<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"sector[]\" value=\"Eventos de competici\u00f3n\" \/><span class=\"wpcf7-list-item-label\">Eventos de competici\u00f3n<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"checkbox\" name=\"sector[]\" value=\"Centros Wellnes\" \/><span class=\"wpcf7-list-item-label\">Centros Wellnes<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p class=\"label\"> Seleccione su servicio de inter\u00e9s *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"service\"><span class=\"wpcf7-form-control wpcf7-checkbox\"><span class=\"wpcf7-list-item first\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Fuentes\" \/><span class=\"wpcf7-list-item-label\">Fuentes<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Lagos o lagunas\" \/><span class=\"wpcf7-list-item-label\">Lagos o lagunas<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Piscinas comerciales\" \/><span class=\"wpcf7-list-item-label\">Piscinas comerciales<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Piscinas deportivas\" \/><span class=\"wpcf7-list-item-label\">Piscinas deportivas<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Piscinas de competici\u00f3n\" \/><span class=\"wpcf7-list-item-label\">Piscinas de competici\u00f3n<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Wellness\" \/><span class=\"wpcf7-list-item-label\">Wellness<\/span><\/label><\/span><span class=\"wpcf7-list-item last has-free-text\"><label><input type=\"checkbox\" name=\"service[]\" value=\"Otros\" \/><span class=\"wpcf7-list-item-label\">Otros<\/span><\/label> <input type=\"text\" name=\"_wpcf7_free_text_service\" class=\"wpcf7-free-text\" \/><\/span><\/span><\/span>\n\t<\/p>\n\t<p class=\"label\"> \u00bfNecesita algo en concreto? *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"needs\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"needs\" value=\"Tengo una pregunta t\u00e9cnica sobre un producto\" \/><span class=\"wpcf7-list-item-label\">Tengo una pregunta t\u00e9cnica sobre un producto<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Necesito asesoramiento t\u00e9cnico para un proyecto\" \/><span class=\"wpcf7-list-item-label\">Necesito asesoramiento t\u00e9cnico para un proyecto<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Necesito asesoramiento t\u00e9cnico para un proyecto y un presupuesto\" \/><span class=\"wpcf7-list-item-label\">Necesito asesoramiento t\u00e9cnico para un proyecto y un presupuesto<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Requiero apoyo espec\u00edfico en dise\u00f1o, asesor\u00eda t\u00e9cnica y estimaci\u00f3n de costos\" \/><span class=\"wpcf7-list-item-label\">Requiero apoyo espec\u00edfico en dise\u00f1o, asesor\u00eda t\u00e9cnica y estimaci\u00f3n de costos<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Tengo preguntas t\u00e9cnicas sobre la instalaci\u00f3n de un proyecto en curso\" \/><span class=\"wpcf7-list-item-label\">Tengo preguntas t\u00e9cnicas sobre la instalaci\u00f3n de un proyecto en curso<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Estoy en fase de licitaci\u00f3n y necesito recomendaciones de productos para cumplir con los requisitos de un proyecto y una oferta comercial\" \/><span class=\"wpcf7-list-item-label\">Estoy en fase de licitaci\u00f3n y necesito recomendaciones de productos para cumplir con los requisitos de un proyecto y una oferta comercial<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Estoy evaluando un proyecto potencial y necesito estudiar su viabilidad y costos asociados\" \/><span class=\"wpcf7-list-item-label\">Estoy evaluando un proyecto potencial y necesito estudiar su viabilidad y costos asociados<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"needs\" value=\"Tengo un proyecto y necesito una oferta comercial\" \/><span class=\"wpcf7-list-item-label\">Tengo un proyecto y necesito una oferta comercial<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"radio\" name=\"needs\" value=\"Me gustar\u00eda distribuir sus productos\" \/><span class=\"wpcf7-list-item-label\">Me gustar\u00eda distribuir sus productos<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p class=\"label\"> Elige la opci\u00f3n de servicio seg\u00fan sus necesidades *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"service_option\"><span class=\"wpcf7-form-control wpcf7-radio\"><span class=\"wpcf7-list-item first\"><label><input type=\"radio\" name=\"service_option\" value=\"Estoy resolviendo problemas cr\u00edticos o finales para completar mi proyecto\" \/><span class=\"wpcf7-list-item-label\">Estoy resolviendo problemas cr\u00edticos o finales para completar mi proyecto<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"service_option\" value=\"Necesito presentar una propuesta o responder a una licitaci\u00f3n pronto\" \/><span class=\"wpcf7-list-item-label\">Necesito presentar una propuesta o responder a una licitaci\u00f3n pronto<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"service_option\" value=\"Estoy en la fase de planificaci\u00f3n detallada y necesito confirmaci\u00f3n para continuar\" \/><span class=\"wpcf7-list-item-label\">Estoy en la fase de planificaci\u00f3n detallada y necesito confirmaci\u00f3n para continuar<\/span><\/label><\/span><span class=\"wpcf7-list-item\"><label><input type=\"radio\" name=\"service_option\" value=\"Estoy en las etapas iniciales de evaluaci\u00f3n y exploraci\u00f3n de opciones para mi proyecto\" \/><span class=\"wpcf7-list-item-label\">Estoy en las etapas iniciales de evaluaci\u00f3n y exploraci\u00f3n de opciones para mi proyecto<\/span><\/label><\/span><span class=\"wpcf7-list-item last\"><label><input type=\"radio\" name=\"service_option\" value=\"Estoy recopilando informaci\u00f3n para un proyecto futuro o una decisi\u00f3n a largo plazo\" \/><span class=\"wpcf7-list-item-label\">Estoy recopilando informaci\u00f3n para un proyecto futuro o una decisi\u00f3n a largo plazo<\/span><\/label><\/span><\/span><\/span>\n\t<\/p>\n\t<p><label> D\u00edganos m\u00e1s sobre su solicitud *<br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"tell-more\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Mensaje\" name=\"tell-more\"><\/textarea><\/span> <\/label>\n\t<\/p>\n<\/div>\n<div class=\"title\">\n\t<p>Para completar el env\u00edo del formulario\n\t<\/p>\n<\/div>\n<div class=\"part\">\n\t<div class=\"title\">\n\t\t<p>Necesitamos su consentimiento\n\t\t<\/p>\n\t<\/div>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"newsletter\"><span class=\"wpcf7-form-control wpcf7-acceptance optional\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"newsletter\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Deseo suscribirme a la newsletter de Fluidra Commercial Pool &#038; Wellness Division, tal y como se indica en la Pol\u00edtica de Privacidad.<\/span><\/label><\/span><\/span><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap\" data-name=\"privacy\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><label><input type=\"checkbox\" name=\"privacy\" value=\"1\" aria-invalid=\"false\" \/><span class=\"wpcf7-list-item-label\">Al enviar este formulario, acepto la Pol\u00edtica de privacidad y consiento el tratamiento de mis datos seg\u00fan lo descrito.<\/span><\/label><\/span><\/span><\/span><br \/>\n\t<div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n\t<\/p>\n\t<div class=\"submit\">\n\t\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Enviar\" \/>\n\t\t<\/p>\n\t<\/div>\n<\/div>\n<\/form>\n<\/div>\n        <\/div>\r\n        <div class=\"continue\">\r\n            <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"210\" height=\"44\" viewBox=\"0 0 210 44\" fill=\"none\">\r\n                <path fill-rule=\"evenodd\" clip-rule=\"evenodd\" d=\"M23 22C23 9.84974 32.8497 0 45 0H164C176.15 0 186 9.84974 186 22C186 34.1503 195.85 44 208 44H219C227.837 44 235 51.1634 235 60C235 68.8366 227.837 76 219 76H186H176H34H23H-9C-17.8366 76 -25 68.8366 -25 60C-25 51.1634 -17.8366 44 -9 44H1C13.1503 44 23 34.1503 23 22Z\" fill=\"#1F7E93\"\/>\r\n                <foreignObject width=\"100%\" height=\"100%\">\r\n                    <div class=\"content\">\r\n                        <div class=\"text\">Continuar<\/div>\r\n                        <img decoding=\"async\" alt=\"icon\" src=\"https:\/\/www.fluidra.com\/wp-content\/themes\/fluidra\/assets\/images\/icons\/dive-down-white.webp\" title=\"\">\r\n                    <\/div>\r\n                <\/foreignObject>\r\n            <\/svg>\r\n        <\/div>\r\n    <\/div>\r\n    <style>\r\n    #ContactForm-block_9871c569364b433b633f07bb0090567f {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px\r\n    }\r\n    @media screen and (max-width: 768px) {\r\n    #ContactForm-block_9871c569364b433b633f07bb0090567f {\r\n        margin-top:px;\r\n        margin-bottom:px;\r\n        padding-top:px;\r\n        padding-bottom:px;\r\n    }\r\n    }\r\n<\/style><\/div>\r\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":8516,"template":"","meta":{"_acf_changed":true},"solution-category":[156],"class_list":["post-9064","solution","type-solution","status-publish","has-post-thumbnail","hentry","solution-category-fountains-es"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/solution\/9064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/solution"}],"about":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/types\/solution"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/media\/8516"}],"wp:attachment":[{"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/media?parent=9064"}],"wp:term":[{"taxonomy":"solution-category","embeddable":true,"href":"https:\/\/www.fluidra.com\/es\/wp-json\/wp\/v2\/solution-category?post=9064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}